{"id":22459,"date":"2020-09-30T00:00:00","date_gmt":"2020-09-30T00:00:00","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=22459"},"modified":"2020-10-02T11:17:27","modified_gmt":"2020-10-02T11:17:27","slug":"suisse-tube-cosmetique-en-bois","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/suisse-tube-cosmetique-en-bois\/","title":{"rendered":"SUISSE : tube cosm\u00e9tique en bois"},"content":{"rendered":"<p>Dans sa gamme de produits EcoDesign, Neopac lance le tube Picea\u2122 \u00e0 base de bois d\u2019\u00e9pic\u00e9a, un emballage durable pour mettre en valeur les produits cosm\u00e9tiques et dentaires naturels.<\/p>\n<p>Le tube compos\u00e9 d\u2019un m\u00e9lange de d\u00e9chets d\u2019\u00e9pic\u00e9a et d\u2019une matrice plastique faite de mati\u00e8res premi\u00e8res \u00e0 base de sucre, contient plus de 95% de mati\u00e8res issues de ressources renouvelables. Le bois d\u2019\u00e9pic\u00e9a provient de for\u00eats europ\u00e9ennes certifi\u00e9es et les fibres de bois sont issues de sciure de menuiseries allemandes. Le tube offre les m\u00eames qualit\u00e9s en termes de propri\u00e9t\u00e9s barri\u00e8re, d\u00e9coration, qualit\u00e9 alimentaire et recyclabilit\u00e9 qu\u2019un tube de poly\u00e9thyl\u00e8ne traditionnel, mais se d\u00e9marque par son bilan carbone 40% moins \u00e9lev\u00e9. Les consommateurs pourront sentir la diff\u00e9rence&nbsp;: la fine sciure de bois rend la surface du tube l\u00e9g\u00e8rement rugueuse. Par ailleurs, le tube a re\u00e7u les certifications Ecocert et Cosmos ainsi que la mention europ\u00e9enne \u00abFood Grade\u00bb qui confirme sa qualit\u00e9 alimentaire.<\/p>\n<p><em>Extrait de la revue n\u00b0 650 &#8211; Ao\u00fbt\/Septembre 2020. Reproduction interdite sauf accord \u00e9crit d&rsquo;Emballage Digest ou mention du support<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans sa gamme de produits EcoDesign, Neopac lance le tube Picea\u2122 \u00e0 base de bois d\u2019\u00e9pic\u00e9a, un emballage durable pour mettre en valeur les produits cosm\u00e9tiques et dentaires naturels.<\/p>","protected":false},"author":1,"featured_media":32459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":0,"footnotes":""},"categories":[5,28,11],"tags":[],"class_list":["post-22459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentaire","category-article-entier","category-emballages"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SUISSE : tube cosm\u00e9tique en bois - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/suisse-tube-cosmetique-en-bois\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUISSE : tube cosm\u00e9tique en bois - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Dans sa gamme de produits EcoDesign, Neopac lance le tube Picea\u2122 \u00e0 base de bois d\u2019\u00e9pic\u00e9a, un emballage durable pour mettre en valeur les produits cosm\u00e9tiques et dentaires naturels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/suisse-tube-cosmetique-en-bois\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-30T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-02T11:17:27+00:00\" \/>\n<meta name=\"author\" content=\"admin_thopel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_thopel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/\"},\"author\":{\"name\":\"admin_thopel\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5\"},\"headline\":\"SUISSE : tube cosm\u00e9tique en bois\",\"datePublished\":\"2020-09-30T00:00:00+00:00\",\"dateModified\":\"2020-10-02T11:17:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/\"},\"wordCount\":207,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg\",\"articleSection\":[\"Alimentaire\",\"Article entier\",\"Emballages\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/\",\"name\":\"SUISSE : tube cosm\u00e9tique en bois - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg\",\"datePublished\":\"2020-09-30T00:00:00+00:00\",\"dateModified\":\"2020-10-02T11:17:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SUISSE : tube cosm\u00e9tique en bois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5\",\"name\":\"admin_thopel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g\",\"caption\":\"admin_thopel\"},\"sameAs\":[\"http:\/\/localhost:8787\/emballage_digest\"],\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_thopel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUISSE : tube cosm\u00e9tique en bois - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/suisse-tube-cosmetique-en-bois\/","og_locale":"en_GB","og_type":"article","og_title":"SUISSE : tube cosm\u00e9tique en bois - Emballage Digest","og_description":"Dans sa gamme de produits EcoDesign, Neopac lance le tube Picea\u2122 \u00e0 base de bois d\u2019\u00e9pic\u00e9a, un emballage durable pour mettre en valeur les produits cosm\u00e9tiques et dentaires naturels.","og_url":"https:\/\/www.emballagedigest.fr\/en\/suisse-tube-cosmetique-en-bois\/","og_site_name":"Emballage Digest","article_published_time":"2020-09-30T00:00:00+00:00","article_modified_time":"2020-10-02T11:17:27+00:00","author":"admin_thopel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_thopel","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/"},"author":{"name":"admin_thopel","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5"},"headline":"SUISSE : tube cosm\u00e9tique en bois","datePublished":"2020-09-30T00:00:00+00:00","dateModified":"2020-10-02T11:17:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/"},"wordCount":207,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg","articleSection":["Alimentaire","Article entier","Emballages"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/","url":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/","name":"SUISSE : tube cosm\u00e9tique en bois - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg","datePublished":"2020-09-30T00:00:00+00:00","dateModified":"2020-10-02T11:17:27+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2020\/REVUE\/sep\/09_20_panorama3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/suisse-tube-cosmetique-en-bois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"SUISSE : tube cosm\u00e9tique en bois"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5","name":"admin_thopel","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g","caption":"admin_thopel"},"sameAs":["http:\/\/localhost:8787\/emballage_digest"],"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_thopel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/22459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=22459"}],"version-history":[{"count":0,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/22459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/32459"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=22459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=22459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=22459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}