{"id":23402,"date":"2021-09-30T00:00:00","date_gmt":"2021-09-30T00:00:00","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=23402"},"modified":"2021-10-14T13:46:16","modified_gmt":"2021-10-14T13:46:16","slug":"des-fruits-proteges-par-un-film-pcr","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/des-fruits-proteges-par-un-film-pcr\/","title":{"rendered":"Des fruits prot\u00e9g\u00e9s par un film PCR"},"content":{"rendered":"<p>Berry Gardens, producteur britannique de fruits \u00e0 noyaux s\u2019est associ\u00e9 \u00e0 Coveris pour la fabrication d\u2019un film d\u2019operculage imprim\u00e9, int\u00e9grant plus de 30% de mat\u00e9riau PCR.<\/p>\n<p>Premi\u00e8re solution \u00e0 partir de d\u00e9chets post-consommation \u00e0 \u00eatre commercialis\u00e9e sur le march\u00e9 anglais, elle est dor\u00e9navant lanc\u00e9e dans le pays sur toutes les gammes de Berry Gardens. Le film permet ainsi de r\u00e9duire l\u2019impact carbone du produit et de supprimer pr\u00e8s de 53 000 kilos de plastique vierge par an. Cette solution alternative r\u00e9pond \u00e9galement \u00e0 l&rsquo;exigence de 30% de contenu recycl\u00e9 pour la taxe sur les emballages plastiques de 2022, avec la possibilit\u00e9 d&rsquo;utiliser jusqu&rsquo;\u00e0 50% de mat\u00e9riau recycl\u00e9. Avec un film rPET scell\u00e9 sur une barquette en PET, Berry Gardens propose une solution mono-mat\u00e9riau enti\u00e8rement recycl\u00e9e et recyclable. Associ\u00e9 \u00e0 la technologie de perforation prim\u00e9e Freshlife\u00ae de Coveris, l\u2019emballage permet d\u2019atteindre une dur\u00e9e de conservation de quatre jours gr\u00e2ce \u00e0 une meilleure gestion de l&rsquo;humidit\u00e9 au sein de la barquette.<br \/>\n<strong>Fournisseur&nbsp;: Coveris<\/strong><\/p>\n<p><em>Extrait de la revue n\u00b0 661 &#8211; Septembre 2021. Reproduction interdite sauf accord \u00e9crit d&rsquo;Emballage Digest ou mention du support<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Berry Gardens, producteur britannique de fruits \u00e0 noyaux s\u2019est associ\u00e9 \u00e0 Coveris pour la fabrication d\u2019un film d\u2019operculage imprim\u00e9, int\u00e9grant plus de 30% de mat\u00e9riau PCR.<\/p>","protected":false},"author":1,"featured_media":33402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":0,"footnotes":""},"categories":[28,4],"tags":[],"class_list":["post-23402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-entier","category-lineaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Des fruits prot\u00e9g\u00e9s par un film PCR - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/des-fruits-proteges-par-un-film-pcr\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des fruits prot\u00e9g\u00e9s par un film PCR - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Berry Gardens, producteur britannique de fruits \u00e0 noyaux s\u2019est associ\u00e9 \u00e0 Coveris pour la fabrication d\u2019un film d\u2019operculage imprim\u00e9, int\u00e9grant plus de 30% de mat\u00e9riau PCR.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/des-fruits-proteges-par-un-film-pcr\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-14T13:46:16+00:00\" \/>\n<meta name=\"author\" content=\"admin_thopel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_thopel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/\"},\"author\":{\"name\":\"admin_thopel\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5\"},\"headline\":\"Des fruits prot\u00e9g\u00e9s par un film PCR\",\"datePublished\":\"2021-09-30T00:00:00+00:00\",\"dateModified\":\"2021-10-14T13:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/\"},\"wordCount\":203,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg\",\"articleSection\":[\"Article entier\",\"Lin\u00e9aires\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/\",\"name\":\"Des fruits prot\u00e9g\u00e9s par un film PCR - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg\",\"datePublished\":\"2021-09-30T00:00:00+00:00\",\"dateModified\":\"2021-10-14T13:46:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des fruits prot\u00e9g\u00e9s par un film PCR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5\",\"name\":\"admin_thopel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g\",\"caption\":\"admin_thopel\"},\"sameAs\":[\"http:\/\/localhost:8787\/emballage_digest\"],\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_thopel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des fruits prot\u00e9g\u00e9s par un film PCR - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/des-fruits-proteges-par-un-film-pcr\/","og_locale":"en_GB","og_type":"article","og_title":"Des fruits prot\u00e9g\u00e9s par un film PCR - Emballage Digest","og_description":"Berry Gardens, producteur britannique de fruits \u00e0 noyaux s\u2019est associ\u00e9 \u00e0 Coveris pour la fabrication d\u2019un film d\u2019operculage imprim\u00e9, int\u00e9grant plus de 30% de mat\u00e9riau PCR.","og_url":"https:\/\/www.emballagedigest.fr\/en\/des-fruits-proteges-par-un-film-pcr\/","og_site_name":"Emballage Digest","article_published_time":"2021-09-30T00:00:00+00:00","article_modified_time":"2021-10-14T13:46:16+00:00","author":"admin_thopel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_thopel","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/"},"author":{"name":"admin_thopel","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5"},"headline":"Des fruits prot\u00e9g\u00e9s par un film PCR","datePublished":"2021-09-30T00:00:00+00:00","dateModified":"2021-10-14T13:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/"},"wordCount":203,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg","articleSection":["Article entier","Lin\u00e9aires"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/","url":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/","name":"Des fruits prot\u00e9g\u00e9s par un film PCR - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg","datePublished":"2021-09-30T00:00:00+00:00","dateModified":"2021-10-14T13:46:16+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2021\/REVUE\/sep\/09_21_lineaire4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/des-fruits-proteges-par-un-film-pcr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Des fruits prot\u00e9g\u00e9s par un film PCR"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5","name":"admin_thopel","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g","caption":"admin_thopel"},"sameAs":["http:\/\/localhost:8787\/emballage_digest"],"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_thopel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/23402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=23402"}],"version-history":[{"count":0,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/23402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/33402"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=23402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=23402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=23402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}