{"id":23909,"date":"2022-03-31T00:00:00","date_gmt":"2022-03-31T00:00:00","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=23909"},"modified":"2022-04-19T14:14:06","modified_gmt":"2022-04-19T14:14:06","slug":"ipack-ima-prepare-sa-prochaine-edition-a-milan","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/","title":{"rendered":"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan"},"content":{"rendered":"<p>Organis\u00e9 \u00e0 Milan, du 3 au 6 mai, Ipack-IMA marque le retour attendu d\u2019un \u00e9v\u00e8nement business autour des technologies de transformation et des mat\u00e9riaux de conditionnement de la fili\u00e8re packaging et process. Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition \u2013 Covid oblige \u2013 le salon se fera le reflet d\u2019une industrie qui n\u2019a jamais ralenti son activit\u00e9 malgr\u00e9 le contexte sanitaire.<\/p>\n<p>Selon l\u2019UCIMA \u2013 l\u2019Union des constructeurs italiens de machines automatiques pour le conditionnement et l\u2019emballage \u2013 le secteur a r\u00e9alis\u00e9 8 435 M\u20ac de CA, soit une hausse de 8% par rapport \u00e0 2020. Une illustration de la capacit\u00e9 de r\u00e9silience et de flexibilit\u00e9 de la fili\u00e8re. L\u2019ensemble des enjeux actuels \u2013 connectivit\u00e9, personnalisation, num\u00e9risation, automatisation et contr\u00f4le \u00e0 distance \u2013 seront autant de pistes d\u2019innovation partag\u00e9es par les 1000 exposants sur place, que ce soit dans l\u2019alimentaire \u2013 quatre grands secteurs seront repr\u00e9sent\u00e9s \u00e0 savoir les p\u00e2tes et la meunerie, les aliments liquides et les boissons, les aliments frais et plats pr\u00e9par\u00e9s ainsi que la confiserie \u2013 mais \u00e9galement les secteurs pharmaceutique, nutritionnel, beaut\u00e9, produits d\u2019entretien et biens industriels. \u00abLa capacit\u00e9 des emballages \u00e0 pr\u00e9server le go\u00fbt, la saveur et l\u2019int\u00e9grit\u00e9 des produits, m\u00eame sur de longues p\u00e9riodes, a \u00e9t\u00e9 red\u00e9couverte. Notamment, la s\u00e9curit\u00e9 que le conditionnement garantit pour \u00e9viter une \u00e9ventuelle contamination lors de la manipulation a \u00e9t\u00e9 salu\u00e9e. Les d\u00e9veloppements li\u00e9s \u00e0 la durabilit\u00e9 deviennent \u00e9galement une pr\u00e9occupation majeure pour l\u2019industrie et principalement pour les fabricants de mat\u00e9riaux qui ont investi massivement dans la recherche et le d\u00e9veloppement \u00e9cologiques, r\u00e9pondant ainsi aux engagements des propri\u00e9taires de marques en faveur de l\u2019\u00e9conomie circulaire. Autant de sujets qui sont devenus incontournables en mati\u00e8re de conditionnement et qui seront pleinement d\u00e9velopp\u00e9s \u00e0 Ipack-IMA\u00bb, a comment\u00e9 Valerio Soli, pr\u00e9sident d\u2019Ipack-IMA.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt2.jpg\" alt=\"Texte Alternatif\" style=\"float:right; margin: 0 0 1em 1em;\" \/>Les mat\u00e9riaux seront d\u2019ailleurs \u00e0 l\u2019honneur avec 200 entreprises du secteur pr\u00e9sentes, facilement identifiables gr\u00e2ce \u00e0 la marque Ipack-Mat du salon, d\u00e9ploy\u00e9es au c\u0153ur du Hall 5. En compl\u00e9ment, l\u2019espace Ipack-IMA Lab rassemblera laboratoires de recherche, instituts de certification et centres sp\u00e9cialis\u00e9s pour \u00e9changer et accompagner les visiteurs dans leur transition d\u2019\u00e9conomie circulaire. En marge du salon, se tiendra \u00e9galement le forum international \u00abPackaging Speaks Green\u00bb, organis\u00e9 par Pack-Media avec le soutien de l\u2019UCIMA, ax\u00e9 sur la durabilit\u00e9 de la cha\u00eene d\u2019approvisionnement du conditionnement.<\/p>\n<p>Mais la principale nouveaut\u00e9, tient dans le fait que Ipack-IMA se tiendra en simultan\u00e9 avec le salon Pharmintech sur le Hall 2, vitrine des technologies de transformation et de conditionnement des industriels de la chimie et de la pharmacie. Les organisateurs misent sur la synergie des deux \u00e9v\u00e9nements pour attirer les professionnels de l\u2019ensemble de ces secteurs. Ipack-IMA n\u2019en reste pas l\u00e0 puisque le salon a choisi de r\u00e9it\u00e9rer le projet \u00abThe Innovation Alliance\u00bb, rassemblant \u00e9galement d\u2019autres salons \u00e0 l\u2019instar de Intralogistica Italia, ax\u00e9e sur la manutention des marchandises et la gestion des entrep\u00f4ts, Print4All, consacr\u00e9e aux technologies d\u2019impression et de conversion industrielles, et la premi\u00e8re \u00e9dition de Greenplast, ax\u00e9e sur la cha\u00eene d\u2019approvisionnement en plastique et en caoutchouc avec un accent sur la durabilit\u00e9 environnementale, l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique et l\u2019\u00e9conomie circulaire. <\/p>\n<p><em>Extrait de la revue n\u00b0 666 &#8211; Mars 2022. Reproduction interdite sauf accord \u00e9crit d&rsquo;Emballage Digest ou mention du support<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Organis\u00e9 \u00e0 Milan, du 3 au 6 mai, Ipack-IMA marque le retour attendu d\u2019un \u00e9v\u00e8nement business autour des technologies de transformation et des mat\u00e9riaux de conditionnement de la fili\u00e8re packaging et process. Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition \u2013 Covid oblige \u2013 le salon se fera le reflet d\u2019une industrie qui n\u2019a jamais ralenti son activit\u00e9 malgr\u00e9 le contexte sanitaire.<\/p>","protected":false},"author":1,"featured_media":33909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":4,"footnotes":""},"categories":[5,28],"tags":[],"class_list":["post-23909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentaire","category-article-entier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Organis\u00e9 \u00e0 Milan, du 3 au 6 mai, Ipack-IMA marque le retour attendu d\u2019un \u00e9v\u00e8nement business autour des technologies de transformation et des mat\u00e9riaux de conditionnement de la fili\u00e8re packaging et process. Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition \u2013 Covid oblige \u2013 le salon se fera le reflet d\u2019une industrie qui n\u2019a jamais ralenti son activit\u00e9 malgr\u00e9 le contexte sanitaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-19T14:14:06+00:00\" \/>\n<meta name=\"author\" content=\"admin_thopel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_thopel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\"},\"author\":{\"name\":\"admin_thopel\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5\"},\"headline\":\"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan\",\"datePublished\":\"2022-03-31T00:00:00+00:00\",\"dateModified\":\"2022-04-19T14:14:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\"},\"wordCount\":586,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg\",\"articleSection\":[\"Alimentaire\",\"Article entier\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\",\"name\":\"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg\",\"datePublished\":\"2022-03-31T00:00:00+00:00\",\"dateModified\":\"2022-04-19T14:14:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5\",\"name\":\"admin_thopel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g\",\"caption\":\"admin_thopel\"},\"sameAs\":[\"http:\/\/localhost:8787\/emballage_digest\"],\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_thopel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/","og_locale":"en_GB","og_type":"article","og_title":"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan - Emballage Digest","og_description":"Organis\u00e9 \u00e0 Milan, du 3 au 6 mai, Ipack-IMA marque le retour attendu d\u2019un \u00e9v\u00e8nement business autour des technologies de transformation et des mat\u00e9riaux de conditionnement de la fili\u00e8re packaging et process. Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition \u2013 Covid oblige \u2013 le salon se fera le reflet d\u2019une industrie qui n\u2019a jamais ralenti son activit\u00e9 malgr\u00e9 le contexte sanitaire.","og_url":"https:\/\/www.emballagedigest.fr\/en\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/","og_site_name":"Emballage Digest","article_published_time":"2022-03-31T00:00:00+00:00","article_modified_time":"2022-04-19T14:14:06+00:00","author":"admin_thopel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_thopel","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/"},"author":{"name":"admin_thopel","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5"},"headline":"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan","datePublished":"2022-03-31T00:00:00+00:00","dateModified":"2022-04-19T14:14:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/"},"wordCount":586,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg","articleSection":["Alimentaire","Article entier"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/","url":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/","name":"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg","datePublished":"2022-03-31T00:00:00+00:00","dateModified":"2022-04-19T14:14:06+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/dotclear\/images\/2022\/REVUE\/mars\/03_22_actu_mt3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/ipack-ima-prepare-sa-prochaine-edition-a-milan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Ipack-IMA pr\u00e9pare sa prochaine \u00e9dition \u00e0 Milan"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/d01fbac1f378e2f5e4096082cdf68ae5","name":"admin_thopel","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cf644f6475359b596b81b10a64f989df38f1238649f7e33f97f69519e42dfbf?s=96&d=mm&r=g","caption":"admin_thopel"},"sameAs":["http:\/\/localhost:8787\/emballage_digest"],"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_thopel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/23909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=23909"}],"version-history":[{"count":0,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/23909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/33909"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=23909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=23909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=23909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}