{"id":38791,"date":"2023-11-08T09:10:18","date_gmt":"2023-11-08T08:10:18","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=38791"},"modified":"2023-11-09T09:20:09","modified_gmt":"2023-11-09T08:20:09","slug":"lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/","title":{"rendered":"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable"},"content":{"rendered":"<p><strong>L\u00e9a Nature, fabricant de produits naturels certifi\u00e9s biologiques, annonce avoir renonc\u00e9 \u00e0 la palette \u00e9change et avoir choisi LPR &#8211; La Palette Rouge (Division d\u2019Euro Pool Group) comme partenaire logistique pour optimiser sa cha\u00eene d&rsquo;approvisionnement et r\u00e9duire son empreinte carbone.<\/strong><\/p>\n\n\n\n<p>Avec plus de 40 marques biologiques dans les secteurs de l\u2019alimentation, de la sant\u00e9, de la beaut\u00e9-hygi\u00e8ne et des soins de la maison, le groupe L\u00e9a Nature s\u2019appuie sur trois entrep\u00f4ts en France pour desservir l\u2019ensemble de ses clients-distributeurs sur le territoire, deux entrep\u00f4ts \u00e0 P\u00e9rigny et un \u00e0 Saintes (d\u00e9partement Charente-Maritime). Jusqu\u2019\u00e0 fin 2022, L\u00e9a Nature utilisait des palettes perdues et des palettes \u00e9change. Le suivi des soldes exc\u00e9dent-d\u00e9ficit \u00e9tait complexe. Cette configuration entra\u00eenait une tension logistique permanente, avec un risque \u00e9lev\u00e9 de rupture de la cha\u00eene d\u2019approvisionnement.<\/p>\n\n\n\n<p>C\u2019est dans ce contexte que L\u00e9a Nature et LPR ont amorc\u00e9 leur coop\u00e9ration au sein de l&rsquo;entrep\u00f4t de P\u00e9rigny sur le flux direct magasin. Ils ont \u00e9tabli des pr\u00e9visions de commandes hebdomadaires, favorisant ainsi une collaboration suivie et mutuelle, offrant une visibilit\u00e9 \u00e0 chaque partie. LPR a commenc\u00e9 \u00e0 fournir des demi-palettes 600 x 800 mm, puis des palettes 800 x 1200 mm en d\u00e9but d&rsquo;ann\u00e9e 2023. \u00c0 ce jour, LPR met \u00e0 disposition de L\u00e9a Nature 125 000 palettes par an.<\/p>\n\n\n\n<p>Ce passage \u00e0 la palette de location a permis \u00e0 L\u00e9a Nature de r\u00e9duire de 47 tonnes les \u00e9missions de CO<sub>2 <\/sub>li\u00e9es \u00e0 la cha\u00eene d&rsquo;approvisionnement en 2023. Prochaine \u00e9tape&nbsp;: L\u00e9a Nature et LPR travaillent d\u00e9j\u00e0 sur l\u2019optimisation des boucles logistiques au sein de l\u2019\u00e9cosyst\u00e8me de l\u2019entreprise, int\u00e9grant tous les acteurs de la cha\u00eene d&rsquo;approvisionnement pour r\u00e9duire encore davantage les \u00e9missions carbone li\u00e9es au transport des palettes et des marchandises. <strong><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u00e9a Nature, fabricant de produits naturels certifi\u00e9s biologiques, annonce avoir renonc\u00e9 \u00e0 la palette \u00e9change et avoir choisi LPR &#8211; La Palette Rouge (Division d\u2019Euro Pool Group) comme partenaire logistique pour optimiser sa cha\u00eene d&rsquo;approvisionnement et r\u00e9duire son empreinte carbone. Avec plus de 40 marques biologiques dans les secteurs de l\u2019alimentation, de la sant\u00e9, de [&hellip;]<\/p>","protected":false},"author":2,"featured_media":38792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":0,"footnotes":""},"categories":[28,11,8],"tags":[],"class_list":["post-38791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-entier","category-emballages","category-industrie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"L\u00e9a Nature, fabricant de produits naturels certifi\u00e9s biologiques, annonce avoir renonc\u00e9 \u00e0 la palette \u00e9change et avoir choisi LPR &#8211; La Palette Rouge (Division d\u2019Euro Pool Group) comme partenaire logistique pour optimiser sa cha\u00eene d&rsquo;approvisionnement et r\u00e9duire son empreinte carbone. Avec plus de 40 marques biologiques dans les secteurs de l\u2019alimentation, de la sant\u00e9, de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T08:10:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T08:20:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable\",\"datePublished\":\"2023-11-08T08:10:18+00:00\",\"dateModified\":\"2023-11-09T08:20:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\"},\"wordCount\":323,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg\",\"articleSection\":[\"Article entier\",\"Emballages\",\"Industrie\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\",\"name\":\"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg\",\"datePublished\":\"2023-11-08T08:10:18+00:00\",\"dateModified\":\"2023-11-09T08:20:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/","og_locale":"en_GB","og_type":"article","og_title":"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable - Emballage Digest","og_description":"L\u00e9a Nature, fabricant de produits naturels certifi\u00e9s biologiques, annonce avoir renonc\u00e9 \u00e0 la palette \u00e9change et avoir choisi LPR &#8211; La Palette Rouge (Division d\u2019Euro Pool Group) comme partenaire logistique pour optimiser sa cha\u00eene d&rsquo;approvisionnement et r\u00e9duire son empreinte carbone. Avec plus de 40 marques biologiques dans les secteurs de l\u2019alimentation, de la sant\u00e9, de [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/","og_site_name":"Emballage Digest","article_published_time":"2023-11-08T08:10:18+00:00","article_modified_time":"2023-11-09T08:20:09+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable","datePublished":"2023-11-08T08:10:18+00:00","dateModified":"2023-11-09T08:20:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/"},"wordCount":323,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg","articleSection":["Article entier","Emballages","Industrie"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/","url":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/","name":"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg","datePublished":"2023-11-08T08:10:18+00:00","dateModified":"2023-11-09T08:20:09+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2023\/11\/LPR.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/lea-nature-signe-avec-lpr-pour-une-supply-chain-efficace-et-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"L\u00e9a Nature signe avec LPR pour une supply chain efficace et durable"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/38791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=38791"}],"version-history":[{"count":1,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/38791\/revisions"}],"predecessor-version":[{"id":38793,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/38791\/revisions\/38793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/38792"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=38791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=38791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=38791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}