{"id":39904,"date":"2024-02-15T00:04:54","date_gmt":"2024-02-14T23:04:54","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=39904"},"modified":"2024-02-15T00:04:56","modified_gmt":"2024-02-14T23:04:56","slug":"coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/","title":{"rendered":"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Coveris annonce la signature et la conclusion d\u2019un nouvel accord strat\u00e9gique : l\u2019acquisition de S&amp;K Label en R\u00e9publique tch\u00e8que. Suite aux r\u00e9centes acquisitions par Coveris de deux usines d\u2019emballages souples en Hongrie et en Pologne, S&amp;K Label, en R\u00e9publique tch\u00e8que, marque la troisi\u00e8me acquisition en Europe de l\u2019Est et la premi\u00e8re d\u2019une entreprise d\u2019\u00e9tiquettes non bas\u00e9e au Royaume-Uni.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que l\u2019un des fabricants d\u2019\u00e9tiquettes les plus technologiquement avanc\u00e9s d\u2019Europe centrale et orientale, S&amp;K LABEL \u2013 cr\u00e9\u00e9e en 1991 et membre de la FINAT depuis 1993 \u2013 repr\u00e9sente un choix strat\u00e9gique id\u00e9al pour l\u2019activit\u00e9 d\u2019\u00e9tiquettes de Coveris visant \u00e0 cr\u00e9er une plate-forme commerciale paneurop\u00e9enne.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris2.jpg\" alt=\"\" class=\"wp-image-39906\" width=\"823\" height=\"431\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris2.jpg 800w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris2-300x157.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris2-768x402.jpg 768w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris2-18x9.jpg 18w\" sizes=\"auto, (max-width: 823px) 100vw, 823px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous sommes ravis de cette opportunit\u00e9 d\u2019investir dans la croissance de notre activit\u00e9 d\u2019\u00e9tiquettes, le d\u00e9veloppement de notre plate-forme et l\u2019\u00e9largissement de notre port\u00e9e g\u00e9ographique. L\u2019acquisition de S&amp;K Label repr\u00e9sente pour nous une excellente opportunit\u00e9 de garantir \u00e0 nos clients des \u00e9tiquettes de haute qualit\u00e9 produites localement, afin de r\u00e9pondre \u00e0 la croissance actuelle et attendue de la demande d\u2019\u00e9tiquettes durables. Cette acquisition nous permettra \u00e9galement de renforcer notre position en Europe continentale&nbsp;\u00bb, explique Christian Kolarik, pdg du groupe Coveris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coveris fabrique des solutions d&#8217;emballage souple et est organis\u00e9e en trois unit\u00e9s commerciales : Films, Flexibles, et Paper. Bas\u00e9e \u00e0 Vienne, le groupe compte 29 sites dans la r\u00e9gion EMEA, avec un total de 4 000 employ\u00e9s.<\/p>","protected":false},"excerpt":{"rendered":"<p>Coveris annonce la signature et la conclusion d\u2019un nouvel accord strat\u00e9gique : l\u2019acquisition de S&amp;K Label en R\u00e9publique tch\u00e8que. Suite aux r\u00e9centes acquisitions par Coveris de deux usines d\u2019emballages souples en Hongrie et en Pologne, S&amp;K Label, en R\u00e9publique tch\u00e8que, marque la troisi\u00e8me acquisition en Europe de l\u2019Est et la premi\u00e8re d\u2019une entreprise d\u2019\u00e9tiquettes non [&hellip;]<\/p>","protected":false},"author":2,"featured_media":39905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":7,"footnotes":""},"categories":[28,10],"tags":[],"class_list":["post-39904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-entier","category-materiaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Coveris annonce la signature et la conclusion d\u2019un nouvel accord strat\u00e9gique : l\u2019acquisition de S&amp;K Label en R\u00e9publique tch\u00e8que. Suite aux r\u00e9centes acquisitions par Coveris de deux usines d\u2019emballages souples en Hongrie et en Pologne, S&amp;K Label, en R\u00e9publique tch\u00e8que, marque la troisi\u00e8me acquisition en Europe de l\u2019Est et la premi\u00e8re d\u2019une entreprise d\u2019\u00e9tiquettes non [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T23:04:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T23:04:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition\",\"datePublished\":\"2024-02-14T23:04:54+00:00\",\"dateModified\":\"2024-02-14T23:04:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\"},\"wordCount\":271,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg\",\"articleSection\":[\"Article entier\",\"Mat\u00e9riaux\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\",\"name\":\"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg\",\"datePublished\":\"2024-02-14T23:04:54+00:00\",\"dateModified\":\"2024-02-14T23:04:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg\",\"width\":800,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/","og_locale":"en_GB","og_type":"article","og_title":"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition - Emballage Digest","og_description":"Coveris annonce la signature et la conclusion d\u2019un nouvel accord strat\u00e9gique : l\u2019acquisition de S&amp;K Label en R\u00e9publique tch\u00e8que. Suite aux r\u00e9centes acquisitions par Coveris de deux usines d\u2019emballages souples en Hongrie et en Pologne, S&amp;K Label, en R\u00e9publique tch\u00e8que, marque la troisi\u00e8me acquisition en Europe de l\u2019Est et la premi\u00e8re d\u2019une entreprise d\u2019\u00e9tiquettes non [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/","og_site_name":"Emballage Digest","article_published_time":"2024-02-14T23:04:54+00:00","article_modified_time":"2024-02-14T23:04:56+00:00","og_image":[{"width":800,"height":496,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition","datePublished":"2024-02-14T23:04:54+00:00","dateModified":"2024-02-14T23:04:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/"},"wordCount":271,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg","articleSection":["Article entier","Mat\u00e9riaux"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/","url":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/","name":"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg","datePublished":"2024-02-14T23:04:54+00:00","dateModified":"2024-02-14T23:04:56+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/02\/Coveris1.jpg","width":800,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/coveris-arrive-sur-le-marche-tcheque-avec-une-nouvelle-acquisition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Coveris arrive sur le march\u00e9 tch\u00e8que avec une nouvelle acquisition"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/39904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=39904"}],"version-history":[{"count":2,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/39904\/revisions"}],"predecessor-version":[{"id":39908,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/39904\/revisions\/39908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/39905"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=39904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=39904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=39904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}