{"id":40038,"date":"2024-03-01T10:50:49","date_gmt":"2024-03-01T09:50:49","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=40038"},"modified":"2024-04-04T09:23:52","modified_gmt":"2024-04-04T07:23:52","slug":"brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/","title":{"rendered":"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu"},"content":{"rendered":"<p><strong>Apr\u00e8s deux ann\u00e9es de discussions, le groupe familial Brodart, imprimeur et transformateur d\u2019emballages souples et \u00e9tiquettes, a officialis\u00e9 le 31 janvier dernier, l\u2019acquisition du groupe Richard Laleu, son concurrent direct, d\u00e9tenu jusqu\u2019ici par Fran\u00e7oise Andres, petite fille du fondateur.<br>C\u2019est une m\u00eame passion pour l\u2019emballage fromager, une histoire familiale similaire, des valeurs communes et une compl\u00e9mentarit\u00e9 \u00e9vidente de leurs produits et technologies qui a conduit \u00e0 ce rapprochement.<\/strong><\/p>\n\n\n\n<p>Cette union permet \u00e0 Brodart Packaging d\u2019int\u00e9grer certes les activit\u00e9s de l\u2019entreprise Richard-Laleu (situ\u00e9 \u00e0 Iteuil, dans la Vienne), sp\u00e9cialiste des emballages fromagers et de beurre (emballages souples, complexes de cuisson, \u00e9tiquettes, manchons ou wrapp), mais \u00e9galement celles de la soci\u00e9t\u00e9 Polykote (situ\u00e9 \u00e0 Gournay-en-Brie en Seine-Maritime), expert en films techniques multicouches pour l\u2019industrie (ramettes de papier et mat\u00e9riaux d\u2019isolation notamment).<br>Le groupe champenois \u00e9largi emploie aujourd\u2019hui 450 salari\u00e9s et compte d\u00e9sormais 10\u00a0sites de production (4 d\u00e9di\u00e9s \u00e0 la production d\u2019\u00e9tiquettes et 6 \u00e0 celle d\u2019emballage souple \u2013 bobines et sacs) pour un chiffre d\u2019affaires global de pr\u00e8s de 90 millions (67 millions avant le rachat). Il devient par la m\u00eame occasion le leader fran\u00e7ais de l\u2019emballage de fromages \u00e0 p\u00e2te molle et un acteur incontournable \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart2.jpg\" alt=\"\" class=\"wp-image-40040\" width=\"833\" height=\"412\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart2.jpg 800w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart2-300x149.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart2-768x380.jpg 768w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart2-18x9.jpg 18w\" sizes=\"auto, (max-width: 833px) 100vw, 833px\" \/><\/figure>\n\n\n\n<p><strong>Des synergies \u00e9videntes<\/strong><br>L\u2019int\u00e9gration du groupe Richard-Laleu s\u2019est impos\u00e9 pour Brodart Packaging comme une formidable opportunit\u00e9. Celle, bien \u00e9videmment, d\u2019\u00e9toffer ses gammes avec des produits et march\u00e9s compl\u00e9mentaires, de d\u00e9couvrir de nouvelles m\u00e9thodes, de massifier ses achats et sur le plan industriel de pouvoir, surtout, mettre en place un back-up de ses process de fabrication d\u2019emballages fromagers, une activit\u00e9 strat\u00e9gique pesant pour 40% du chiffre d\u2019affaires du groupe Brodart Packaging. Jusqu\u2019alors, ce back-up n\u2019existait que sur une partie du process, l\u2019impression et la d\u00e9coupe de bobines. Dor\u00e9navant, Brodart poss\u00e8de deux sites qui lui permettent une duplication compl\u00e8te des process, s\u00e9curisant ainsi ses productions clients.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart3.jpg\" alt=\"\" class=\"wp-image-40041\" width=\"830\" height=\"561\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart3.jpg 800w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart3-300x203.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart3-768x519.jpg 768w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart3-18x12.jpg 18w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/figure>\n\n\n\n<p>En ce qui concerne la soci\u00e9t\u00e9 Polykote, Brodart Packaging envisage, \u00e0 plus ou moins long terme, d\u2019en faire son laboratoire interne et de s\u2019appuyer sur son expertise pour d\u00e9velopper un site de production de supports enduits qui permettra de r\u00e9pondre \u00e0 une demande croissante du march\u00e9 pour ce type de supports.<br>L\u2019enthousiasme des \u00e9quipes est r\u00e9el et l\u2019\u00e9tude d\u2019autres synergies possibles en cours.<br>Pour accompagner son portefeuille \u00e9largi, le groupe a d\u2019ores et d\u00e9j\u00e0 proc\u00e9d\u00e9 \u00e0 une r\u00e9organisation de sa direction commerciale et \u00e0 son renforcement avec le recrutement d\u2019une nouvelle directrice pour son activit\u00e9 flexible. Son arriv\u00e9e est pr\u00e9vue courant mars.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart4.jpg\" alt=\"\" class=\"wp-image-40042\" width=\"840\" height=\"543\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart4.jpg 800w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart4-300x194.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart4-768x496.jpg 768w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart4-18x12.jpg 18w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><figcaption>Machine d\u2019impression Comexi F4 install\u00e9e sur le site Richard Laleu depuis 2021<\/figcaption><\/figure>\n\n\n\n<p><strong>Un \u00e9largissement de son assise \u00e0 l\u2019international<\/strong><br>La d\u00e9cision strat\u00e9gique du rachat de Richard-Laleu ouvre \u00e9galement de nouvelles perspectives en dehors des fronti\u00e8res pour le groupe Brodart qui r\u00e9alise d\u00e9j\u00e0 11% de son chiffre d\u2019affaires \u00e0 l\u2019export.<br>Le groupe \u00e9tait jusqu\u2019alors pr\u00e9sent en Europe, au Canada, aux Etats-Unis, en Australie, Nouvelle-Z\u00e9lande, Russie et au Japon. Richard-Laleu lui permet d\u00e9sormais d\u2019acc\u00e9der \u00e0 de nouvelles zones parmi lesquelles l\u2019Am\u00e9rique Latine ou encore l\u2019Angleterre.<\/p>\n\n\n\n<p><strong>110 ans et plus dynamique que jamais<\/strong><br>Les projets se bousculent chez Brodart Packaging. Le groupe envisage en effet la modernisation de plusieurs de ses usines au cours des deux prochaines ann\u00e9es gr\u00e2ce \u00e0 un investissement de pr\u00e8s de 13 millions d\u2019euros. Au nombre de ces projets, le doublement de la surface de son usine d\u2019\u00e9tiquettes de La Halle et la construction d\u2019un nouvel atelier sur un terrain r\u00e9cemment acquis \u00e0 Breger Centre. C\u00f4t\u00e9 machine, le groupe \u00e9tudie l\u2019achat d\u2019une nouvelle ligne d\u2019impression. Flexo ou offset le choix n\u2019est pas encore arr\u00eat\u00e9.<\/p>\n\n\n\n<p><strong><em>Pour en savoir plus, rendez-vous du 12 au 14 mars au CFIA de Rennes, Hall 9 &#8211; Stand D40.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"91\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart5-1.jpg\" alt=\"\" class=\"wp-image-40044\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart5-1.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart5-1-18x5.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption><strong><a href=\"http:\/\/www.brodart-packaging.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.brodart-packaging.fr\/<\/a><\/strong><\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s deux ann\u00e9es de discussions, le groupe familial Brodart, imprimeur et transformateur d\u2019emballages souples et \u00e9tiquettes, a officialis\u00e9 le 31 janvier dernier, l\u2019acquisition du groupe Richard Laleu, son concurrent direct, d\u00e9tenu jusqu\u2019ici par Fran\u00e7oise Andres, petite fille du fondateur.C\u2019est une m\u00eame passion pour l\u2019emballage fromager, une histoire familiale similaire, des valeurs communes et une compl\u00e9mentarit\u00e9 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":40039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":5,"footnotes":""},"categories":[5,28],"tags":[],"class_list":["post-40038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentaire","category-article-entier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s deux ann\u00e9es de discussions, le groupe familial Brodart, imprimeur et transformateur d\u2019emballages souples et \u00e9tiquettes, a officialis\u00e9 le 31 janvier dernier, l\u2019acquisition du groupe Richard Laleu, son concurrent direct, d\u00e9tenu jusqu\u2019ici par Fran\u00e7oise Andres, petite fille du fondateur.C\u2019est une m\u00eame passion pour l\u2019emballage fromager, une histoire familiale similaire, des valeurs communes et une compl\u00e9mentarit\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T09:50:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T07:23:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu\",\"datePublished\":\"2024-03-01T09:50:49+00:00\",\"dateModified\":\"2024-04-04T07:23:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\"},\"wordCount\":687,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg\",\"articleSection\":[\"Alimentaire\",\"Article entier\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\",\"name\":\"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg\",\"datePublished\":\"2024-03-01T09:50:49+00:00\",\"dateModified\":\"2024-04-04T07:23:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg\",\"width\":800,\"height\":552},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/","og_locale":"en_GB","og_type":"article","og_title":"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu - Emballage Digest","og_description":"Apr\u00e8s deux ann\u00e9es de discussions, le groupe familial Brodart, imprimeur et transformateur d\u2019emballages souples et \u00e9tiquettes, a officialis\u00e9 le 31 janvier dernier, l\u2019acquisition du groupe Richard Laleu, son concurrent direct, d\u00e9tenu jusqu\u2019ici par Fran\u00e7oise Andres, petite fille du fondateur.C\u2019est une m\u00eame passion pour l\u2019emballage fromager, une histoire familiale similaire, des valeurs communes et une compl\u00e9mentarit\u00e9 [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/","og_site_name":"Emballage Digest","article_published_time":"2024-03-01T09:50:49+00:00","article_modified_time":"2024-04-04T07:23:52+00:00","og_image":[{"width":800,"height":552,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu","datePublished":"2024-03-01T09:50:49+00:00","dateModified":"2024-04-04T07:23:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/"},"wordCount":687,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg","articleSection":["Alimentaire","Article entier"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/","url":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/","name":"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg","datePublished":"2024-03-01T09:50:49+00:00","dateModified":"2024-04-04T07:23:52+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/03\/brodart1.jpg","width":800,"height":552},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/brodart-renforce-sa-position-sur-le-marche-de-lemballage-fromager-avec-lacquisition-du-groupe-richard-laleu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Brodart renforce sa position sur le march\u00e9 de l\u2019emballage fromager avec l\u2019acquisition du groupe Richard Laleu"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/40038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=40038"}],"version-history":[{"count":2,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/40038\/revisions"}],"predecessor-version":[{"id":40046,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/40038\/revisions\/40046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/40039"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=40038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=40038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=40038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}