{"id":41293,"date":"2024-06-17T09:12:03","date_gmt":"2024-06-17T07:12:03","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=41293"},"modified":"2024-06-17T09:12:05","modified_gmt":"2024-06-17T07:12:05","slug":"sidel-renforce-sa-presence-en-asie","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/sidel-renforce-sa-presence-en-asie\/","title":{"rendered":"Sidel renforce sa pr\u00e9sence en Asie"},"content":{"rendered":"<p><strong>Sidel, fournisseur d\u2019\u00e9quipements, de services et de solutions de lignes compl\u00e8tes pour le conditionnement des liquides, des produits alimentaires, des produits d\u2019hygi\u00e8ne du corps et de la maison, a ouvert un nouveau bureau \u00e0 Almaty, au Kazakhstan, le 12&nbsp;juin dernier. Cette d\u00e9cision strat\u00e9gique vise \u00e0 rapprocher l\u2019expertise de Sidel de ses clients et \u00e0 accompagner au mieux leur croissance dans la r\u00e9gion.<\/strong>&nbsp;&nbsp;<\/p>\n\n\n\n<p>Sidel intervient dans la r\u00e9gion Asie centrale et Caucase (ACC) depuis plus de dix&nbsp;ans. Cette r\u00e9gion est un march\u00e9 non n\u00e9gligeable, car le Kazakhstan, l\u2019Ouzb\u00e9kistan, l\u2019Azerba\u00efdjan, le Tadjikistan, le Turkm\u00e9nistan, le Kirghizistan, la G\u00e9orgie et l\u2019Arm\u00e9nie enregistrent un essor de leur PIB et de leur revenu disponible. S\u2019appuyant sur les solides relations que Sidel a d\u00e9j\u00e0 nou\u00e9es avec les producteurs de biens de grande consommation de la r\u00e9gion CCA, l\u2019entreprise continuera d\u2019investir massivement dans cette r\u00e9gion, en fournissant ses solutions et services de haute qualit\u00e9 tout en r\u00e9pondant aux besoins du march\u00e9 local.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel2.jpg\" alt=\"\" class=\"wp-image-41295\" width=\"828\" height=\"596\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel2.jpg 800w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel2-300x216.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel2-768x553.jpg 768w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel2-18x12.jpg 18w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/figure>\n\n\n\n<p>\u00ab&nbsp;La proximit\u00e9 avec nos clients nous permettra de mieux comprendre l\u2019\u00e9volution du march\u00e9 et les tendances de consommation afin de fournir des solutions encore plus personnalis\u00e9es aux entreprises locales et d\u2019accompagner l\u2019essor de nos clients \u00e0 mesure que la r\u00e9gion se d\u00e9veloppe&nbsp;\u00bb, commente Marina&nbsp;De&nbsp;Barros, EVP Customer Management ECA chez Sidel.<\/p>\n\n\n\n<p>Le nouveau bureau donnera aux producteurs un acc\u00e8s direct \u00e0 l\u2019expertise r\u00e9gionale de Sidel, notamment \u00e0 la gestion de projet locale, aux solutions d\u2019ing\u00e9nierie avanc\u00e9es et aux services de support sur le terrain qui comprennent les nuances du march\u00e9 local et r\u00e9pondent \u00e0 ses besoins. \u00ab&nbsp;En combinant notre expertise mondiale en mati\u00e8re de solutions d\u2019emballage avanc\u00e9es avec notre savoir-faire et notre pr\u00e9sence au niveau local, nous continuerons \u00e0 apporter des innovations \u00e0 la r\u00e9gion dans plusieurs domaines&nbsp;: conception des emballages, soufflage, remplissage, \u00e9tiquetage, encaissage, palettisation et une multitude de services pour optimiser les performances des lignes de nos clients&nbsp;\u00bb, ajoute Gilles&nbsp;Bouvier, Services VP de la zone&nbsp;ECA chez Sidel.<\/p>\n\n\n\n<p>Sidel s\u2019est \u00e9galement engag\u00e9 \u00e0 investir sur le march\u00e9 de l\u2019emploi en s\u2019appuyant sur les talents locaux et en d\u00e9veloppant leurs comp\u00e9tences sur toutes les fonctions op\u00e9rationnelles cl\u00e9s&nbsp;: ventes, gestion de projet et services. \u00ab&nbsp;Nous souhaitons contribuer \u00e0 l\u2019essor \u00e9conomique de la r\u00e9gion afin d\u2019assurer un d\u00e9veloppement durable et responsable. En renfor\u00e7ant notre pr\u00e9sence, nous r\u00e9affirmons notre engagement \u00e0 \u00eatre un partenaire de confiance pour nos clients qui souhaitent se d\u00e9velopper dans la r\u00e9gion&nbsp;\u00bb, commente Guillaume&nbsp;Rolland, VP Sales Beverages ECA chez Sidel.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sidel, fournisseur d\u2019\u00e9quipements, de services et de solutions de lignes compl\u00e8tes pour le conditionnement des liquides, des produits alimentaires, des produits d\u2019hygi\u00e8ne du corps et de la maison, a ouvert un nouveau bureau \u00e0 Almaty, au Kazakhstan, le 12&nbsp;juin dernier. Cette d\u00e9cision strat\u00e9gique vise \u00e0 rapprocher l\u2019expertise de Sidel de ses clients et \u00e0 accompagner [&hellip;]<\/p>","protected":false},"author":2,"featured_media":41294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":8,"footnotes":""},"categories":[5,28,35],"tags":[],"class_list":["post-41293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentaire","category-article-entier","category-machines-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sidel renforce sa pr\u00e9sence en Asie - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/sidel-renforce-sa-presence-en-asie\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sidel renforce sa pr\u00e9sence en Asie - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Sidel, fournisseur d\u2019\u00e9quipements, de services et de solutions de lignes compl\u00e8tes pour le conditionnement des liquides, des produits alimentaires, des produits d\u2019hygi\u00e8ne du corps et de la maison, a ouvert un nouveau bureau \u00e0 Almaty, au Kazakhstan, le 12&nbsp;juin dernier. Cette d\u00e9cision strat\u00e9gique vise \u00e0 rapprocher l\u2019expertise de Sidel de ses clients et \u00e0 accompagner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/sidel-renforce-sa-presence-en-asie\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T07:12:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T07:12:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"519\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Sidel renforce sa pr\u00e9sence en Asie\",\"datePublished\":\"2024-06-17T07:12:03+00:00\",\"dateModified\":\"2024-06-17T07:12:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg\",\"articleSection\":[\"Alimentaire\",\"Article entier\",\"Machines\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/\",\"name\":\"Sidel renforce sa pr\u00e9sence en Asie - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg\",\"datePublished\":\"2024-06-17T07:12:03+00:00\",\"dateModified\":\"2024-06-17T07:12:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg\",\"width\":800,\"height\":519},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sidel renforce sa pr\u00e9sence en Asie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sidel renforce sa pr\u00e9sence en Asie - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/sidel-renforce-sa-presence-en-asie\/","og_locale":"en_GB","og_type":"article","og_title":"Sidel renforce sa pr\u00e9sence en Asie - Emballage Digest","og_description":"Sidel, fournisseur d\u2019\u00e9quipements, de services et de solutions de lignes compl\u00e8tes pour le conditionnement des liquides, des produits alimentaires, des produits d\u2019hygi\u00e8ne du corps et de la maison, a ouvert un nouveau bureau \u00e0 Almaty, au Kazakhstan, le 12&nbsp;juin dernier. Cette d\u00e9cision strat\u00e9gique vise \u00e0 rapprocher l\u2019expertise de Sidel de ses clients et \u00e0 accompagner [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/sidel-renforce-sa-presence-en-asie\/","og_site_name":"Emballage Digest","article_published_time":"2024-06-17T07:12:03+00:00","article_modified_time":"2024-06-17T07:12:05+00:00","og_image":[{"width":800,"height":519,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Sidel renforce sa pr\u00e9sence en Asie","datePublished":"2024-06-17T07:12:03+00:00","dateModified":"2024-06-17T07:12:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/"},"wordCount":474,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg","articleSection":["Alimentaire","Article entier","Machines"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/","url":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/","name":"Sidel renforce sa pr\u00e9sence en Asie - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg","datePublished":"2024-06-17T07:12:03+00:00","dateModified":"2024-06-17T07:12:05+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/sidel1.jpg","width":800,"height":519},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/sidel-renforce-sa-presence-en-asie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Sidel renforce sa pr\u00e9sence en Asie"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/41293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=41293"}],"version-history":[{"count":2,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/41293\/revisions"}],"predecessor-version":[{"id":41297,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/41293\/revisions\/41297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/41294"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=41293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=41293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=41293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}