{"id":41329,"date":"2024-06-21T00:14:32","date_gmt":"2024-06-20T22:14:32","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=41329"},"modified":"2024-06-21T08:08:56","modified_gmt":"2024-06-21T06:08:56","slug":"swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/","title":{"rendered":"Swiss Food &#038; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Swiss Food &amp; Nutrition Valley, ainsi que ses partenaires Nestl\u00e9 et Tetra Pak, ont r\u00e9uni plus de 60 partenaires suisses et europ\u00e9ens lors d&rsquo;un \u00e9v\u00e9nement d\u2019envergure nationale, \u00e0 Berne cette semaine. Ce projet commun est con\u00e7u afin de mettre en lumi\u00e8re certaines approches parmi les plus prometteuses en mati\u00e8re de composants d&#8217;emballages durables, et de favoriser l\u2019innovation par la collaboration et l\u2019innovation.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Christina Senn-Jakobsen, CEO de Swiss Food &amp; Nutrition Valley, d\u00e9clare \u00e0 propos de l\u2019\u00e9v\u00e8nement : \u00ab\u00a0cet \u00e9v\u00e8nement propose de mettre en avant l\u2019incroyable potentiel de l\u2019innovation collaborative. \u00a0Les d\u00e9fis li\u00e9s aux emballages durables ne peuvent pas \u00eatre r\u00e9solus isol\u00e9ment. C\u2019est pourquoi, la collaboration entre les start-ups, les multinationales, les institutions de recherche et les organismes gouvernementaux est cruciale\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rob Hoitink, en charge de la R&amp;D emballage au niveau Mondial chez Nestl\u00e9, a ajout\u00e9\u00a0: \u00ab\u00a0l\u2019innovation est la cl\u00e9 pour nous permettre d\u2019atteindre notre ambition d\u2019un emballage 100% recyclable ou r\u00e9utilisable. L\u2019\u00e9v\u00e9nement auquel nous assistions ce jour met en lumi\u00e8re, l\u2019importance vitale de la R&amp;D dans l&rsquo;ensemble de l&rsquo;\u00e9cosyst\u00e8me pour acc\u00e9l\u00e9rer le d\u00e9veloppement et la mise en \u0153uvre de nouvelles solutions\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et Gustavo Barros, directeur des partenariats R&amp;D chez Tetra Pak, de conclure : \u00ab\u00a0la collaboration avec nos clients, fournisseurs et acteurs de l\u2019industrie, a \u00e9t\u00e9 au c\u0153ur de notre trajectoire durable. Notre engagement en faveur du d\u00e9veloppement durable nous pousse constamment \u00e0 explorer de nouveaux mat\u00e9riaux et de nouvelles technologies. \u00a0Aujourd&rsquo;hui, nous avons \u00e9tabli des liens avec plusieurs innovateurs dont les recherches peuvent nous aider \u00e0 progresser encore davantage. Nous nous r\u00e9jouissons de poursuivre ces \u00e9changes\u00a0\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>Swiss Food &amp; Nutrition Valley, ainsi que ses partenaires Nestl\u00e9 et Tetra Pak, ont r\u00e9uni plus de 60 partenaires suisses et europ\u00e9ens lors d&rsquo;un \u00e9v\u00e9nement d\u2019envergure nationale, \u00e0 Berne cette semaine. Ce projet commun est con\u00e7u afin de mettre en lumi\u00e8re certaines approches parmi les plus prometteuses en mati\u00e8re de composants d&#8217;emballages durables, et de [&hellip;]<\/p>","protected":false},"author":2,"featured_media":41330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":4,"footnotes":""},"categories":[5,28,10,81],"tags":[],"class_list":["post-41329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentaire","category-article-entier","category-materiaux","category-packaging"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Swiss Food &amp; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swiss Food &amp; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Swiss Food &amp; Nutrition Valley, ainsi que ses partenaires Nestl\u00e9 et Tetra Pak, ont r\u00e9uni plus de 60 partenaires suisses et europ\u00e9ens lors d&rsquo;un \u00e9v\u00e9nement d\u2019envergure nationale, \u00e0 Berne cette semaine. Ce projet commun est con\u00e7u afin de mettre en lumi\u00e8re certaines approches parmi les plus prometteuses en mati\u00e8re de composants d&#8217;emballages durables, et de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T22:14:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T06:08:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Swiss Food &#038; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak\",\"datePublished\":\"2024-06-20T22:14:32+00:00\",\"dateModified\":\"2024-06-21T06:08:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\"},\"wordCount\":307,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg\",\"articleSection\":[\"Alimentaire\",\"Article entier\",\"Mat\u00e9riaux\",\"Packaging\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\",\"name\":\"Swiss Food & Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg\",\"datePublished\":\"2024-06-20T22:14:32+00:00\",\"dateModified\":\"2024-06-21T06:08:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg\",\"width\":800,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swiss Food &#038; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Swiss Food & Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/","og_locale":"en_GB","og_type":"article","og_title":"Swiss Food & Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak - Emballage Digest","og_description":"Swiss Food &amp; Nutrition Valley, ainsi que ses partenaires Nestl\u00e9 et Tetra Pak, ont r\u00e9uni plus de 60 partenaires suisses et europ\u00e9ens lors d&rsquo;un \u00e9v\u00e9nement d\u2019envergure nationale, \u00e0 Berne cette semaine. Ce projet commun est con\u00e7u afin de mettre en lumi\u00e8re certaines approches parmi les plus prometteuses en mati\u00e8re de composants d&#8217;emballages durables, et de [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/","og_site_name":"Emballage Digest","article_published_time":"2024-06-20T22:14:32+00:00","article_modified_time":"2024-06-21T06:08:56+00:00","og_image":[{"width":800,"height":496,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Swiss Food &#038; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak","datePublished":"2024-06-20T22:14:32+00:00","dateModified":"2024-06-21T06:08:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/"},"wordCount":307,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg","articleSection":["Alimentaire","Article entier","Mat\u00e9riaux","Packaging"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/","url":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/","name":"Swiss Food & Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg","datePublished":"2024-06-20T22:14:32+00:00","dateModified":"2024-06-21T06:08:56+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/06\/Swiss-Food.jpg","width":800,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/swiss-food-nutrition-valley-sassocie-a-nestle-et-tetra-pak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Swiss Food &#038; Nutrition Valley s\u2019associe \u00e0 Nestl\u00e9 et Tetra Pak"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/41329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=41329"}],"version-history":[{"count":1,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/41329\/revisions"}],"predecessor-version":[{"id":41331,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/41329\/revisions\/41331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/41330"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=41329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=41329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=41329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}