{"id":42217,"date":"2024-09-30T18:08:00","date_gmt":"2024-09-30T16:08:00","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=42217"},"modified":"2024-10-06T18:10:16","modified_gmt":"2024-10-06T16:10:16","slug":"emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/","title":{"rendered":"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9"},"content":{"rendered":"<p><strong>En France, environ 60% des cas d\u2019intoxication accidentelle chez les enfants sont li\u00e9s aux m\u00e9dicaments, les plus jeunes (1 \u00e0 3 ans) \u00e9tant particuli\u00e8rement \u00e0 risque. En r\u00e9ponse aux r\u00e9glementations mondiales et aux attentes des industries, les fabricants (SGD Pharma, Neopac, Sanner Group, SnapSlide, Rieke, Silgan Dispensing) d\u00e9veloppent des emballages certifi\u00e9s r\u00e9sistants aux enfants (Child Resistant &#8211; CR) tout en \u00e9tant faciles \u00e0 ouvrir pour les personnes \u00e2g\u00e9es (Senior Friendly &#8211; SF). Ils veillent \u00e9galement \u00e0 ce que ces solutions soient recyclables et \u00e0 faible empreinte environnementale pour renforcer leur durabilit\u00e9.<\/strong><\/p>\n\n\n\n<p>Selon l\u2019Institut de recherche sur le march\u00e9 des emballages (IVM) en Allemagne, on constate une r\u00e9duction des cas d\u2019empoisonnement mortel dans les pays ayant adopt\u00e9 des r\u00e9glementations sur les emballages \u00e0 l\u2019\u00e9preuve des enfants. Dr Rolf Abelmann, directeur g\u00e9n\u00e9ral de IVM Childsafe, souligne que ces emballages, certifi\u00e9s CR-SF, garantissent une s\u00e9curit\u00e9 pour les enfants tout en restant faciles \u00e0 ouvrir pour les personnes \u00e2g\u00e9es. Les solutions couramment utilis\u00e9es incluent les bouchons \u00e0 vis \u00abpush &amp; turn\u00bb et les blisters pour les comprim\u00e9s. Les normes internationales en vigueur, comme ISO 8317 (2015) et ISO 14375 (2018) ou US16 CFR 1700.200, r\u00e9gissent ces emballages. \u00abAux \u00c9tats-Unis, la s\u00e9curit\u00e9 enfant est d\u00e9sormais un standard, tandis qu\u2019en Europe, on observe une croissance de l\u2019utilisation d\u2019emballages certifi\u00e9s CR-SF pour pr\u00e9venir les risques d\u2019ingestion accidentelle\u00bb, indique Najet Mebarki, directrice Management Produit &amp; Innovation chez SGD Pharma.<\/p>\n\n\n\n<p><strong>Solutions cl\u00e9s en main et recyclables \u00ab\u00a0made in Europe\u00a0\u00bb<\/strong><br>SGD Pharma, leader des flacons en verre moul\u00e9, collabore avec des fabricants de bouchons pour offrir des solutions compl\u00e8tes d\u2019emballage, incluant des syst\u00e8mes de fermeture s\u00e9curis\u00e9s pour les enfants (CR-SF), certifi\u00e9es par des organismes comme IVM Childsafe. Un exemple r\u00e9cent est la gamme Ensiemo, lanc\u00e9e en 2020 aux \u00c9tats-Unis pour l\u2019huile de CBD, qui comprend des flacons et compte-gouttes en verre jaune et blanc de qualit\u00e9 pharmaceutique (du 5 au 100 ml) avec fermeture CRC-SF et t\u00e9moin d\u2019inviolabilit\u00e9. \u00abCette gamme s\u2019utilise \u00e9galement pour les huiles essentielles et s\u00e9rums dermo-cosm\u00e9tiques\u00bb, indique Najet Mebarki. La fonctionnalit\u00e9 s\u00e9curit\u00e9 enfant a \u00e9t\u00e9 int\u00e9gr\u00e9e d\u00e8s le d\u00e9part dans son d\u00e9veloppement au travers d\u2019un bouchon PP28 ou DIN 18 et d\u2019une pipette en verre de type III en version CR-SF. La soci\u00e9t\u00e9 Clos S\u00e9pale, fabricant d\u2019huile de CBD en France, utilise la gamme Ensiemo en flacons compte-gouttes de 30 ml pour les animaux et de 10 ml pour l\u2019homme par voie sublinguale. \u00abNotre pr\u00e9occupation est la s\u00e9curit\u00e9, note Nicolas Chapulliot, pdg fondateur de la soci\u00e9t\u00e9. Au-del\u00e0 d\u2019avoir un emballage \u00e0 l\u2019\u00e9preuve des enfants, nous avons choisi un flacon en verre pour la neutralit\u00e9 chimique et pharmaceutique avec une production locale. Le verre est recyclable \u00e0 l\u2019infini. De plus, la pipette en verre et la t\u00e9tine en TPE qui composent le compte-goutte peuvent \u00eatre facilement s\u00e9par\u00e9s et recycl\u00e9s\u00bb.<\/p>\n\n\n\n<p><strong>Tube mini CR et sans aluminium<\/strong><br>De son c\u00f4t\u00e9, Neopac se concentre sur la production de bouchons \u00e0 l\u2019\u00e9preuve des enfants r\u00e9pondant aux exigences internationales strictes comme l\u2019ISO 8317 et la norme am\u00e9ricaine 16 CFR \u00a7 1700.20. \u00abCes solutions sont principalement utilis\u00e9es dans la sant\u00e9 pour des produits \u00e0 haute concentration, tels que les traitements sp\u00e9cialis\u00e9s, les antiparasitaires pour animaux, et les e-liquides toxiques, pr\u00e9sente Cornelia Schmidt, responsable marketing d\u2019Hoffmann Neopac.<br>Le fabricant a d\u00e9velopp\u00e9 des solutions polyvalentes avec des options personnalisables pour r\u00e9pondre aux besoins des clients sur les diff\u00e9rents march\u00e9s. Ce qui inclut le plus petit tube CR-SF disponible sur le march\u00e9 \u00e0 partir de 1 ml et une gamme allant jusqu\u2019\u00e0 125 ml avec des diam\u00e8tres de 10 \u00e0 40 mm. \u00abNotre Drug Master File (DMF) pour nos tubes Polyfoil\u00ae aux \u00c9tats-Unis renforce \u00e9galement notre engagement envers la s\u00e9curit\u00e9 et la qualit\u00e9\u00bb, ajoute Cornelia Schmidt. Un point d\u2019attention pour les tubes de petite taille reste leur recyclabilit\u00e9, qui est difficile \u00e0 r\u00e9aliser avec les m\u00e9thodes de tri traditionnelles dans les installations actuelles. \u00abC\u2019est pourquoi nous \u00e9tudions la possibilit\u00e9 d\u2019utiliser des technologies d\u2019impression avanc\u00e9es ou des marqueurs sp\u00e9ciaux d\u00e9tectables par cam\u00e9ra optique pour am\u00e9liorer cette \u00e9tape\u00bb, pointe-t-elle.<br>Et c\u00f4t\u00e9 nouveaut\u00e9\u00a0cette ann\u00e9e, le tube mini Polyfoil\u00ae MMB sans aluminium, avec des diam\u00e8tres de 13,5 et 16 mm, sera pr\u00e9sent\u00e9 au prochain CPhI Milan, offrant une structure mono-mat\u00e9riau, une empreinte carbone r\u00e9duite, et une s\u00e9curit\u00e9 enfant optimale.<\/p>\n\n\n\n<p><strong>Piluliers distributeurs modernes<\/strong><br>Dans la gamme des piluliers, Sanner Packaging met en avant son emballage Sanner TabTec CR, con\u00e7u pour \u00eatre \u00e0 l\u2019\u00e9preuve des enfants et adapt\u00e9 aux personnes \u00e2g\u00e9es, avec son m\u00e9canisme \u00e0 pression et bascule (Press &amp; Flip) \u00e0 ouvrir des deux mains, et conforme aux normes ISO\u00a08317 (2015) et PPPA\u00a016\u00a0CFR\u00a01700.20. De forme ronde, arrondie et nomade, il se glisse facilement dans une poche. Disponible dans une vari\u00e9t\u00e9 de couleurs, il r\u00e9pond \u00e9galement aux besoins de diff\u00e9renciation des marques. Parmi ses autres caract\u00e9ristiques, le pilulier prot\u00e8ge les doses solides de m\u00e9dicaments sensibles \u00e0 la lumi\u00e8re et \u00e0 l\u2019humidit\u00e9 gr\u00e2ce \u00e0 son dessicateur int\u00e9gr\u00e9. Le bec verseur dans l\u2019ouverture garantit \u00e9galement un dosage hygi\u00e9nique et facile. \u00abCe pilulier garantit une s\u00e9curit\u00e9 et une fiabilit\u00e9 optimales pour diverses applications, selon Christian Classen, directeur commercial chez Sanner Group, comme le cannabis m\u00e9dical, le sevrage tabagique, les analg\u00e9siques, les antid\u00e9presseurs et les m\u00e9dicaments cardiovasculaires\u00bb.<\/p>\n\n\n\n<p><strong>Bouchon inclusif et convivial<\/strong><br>Parmi les nouveaut\u00e9s r\u00e9centes, l\u2019am\u00e9ricain SnapSlide propose une alternative plus inclusive et conviviale aux bouchons \u00abpush &amp; turn\u00bb traditionnels. Le bouchon SnapSlide, avec un m\u00e9canisme d\u2019ouverture en deux \u00e9tapes, permet selon Rocky Batzel, son pdg, une utilisation s\u00e9curis\u00e9e d\u2019une seule main, tout en \u00e9tant r\u00e9sistant aux enfants. Cette innovation ergonomique est adaptable \u00e0 tous les emballages, selon lui, et utilise 25% de plastique en moins par rapport aux piluliers classiques am\u00e9ricains. Elle a re\u00e7u le prix AmeriStar d\u00e9cern\u00e9 par l\u2019IoPP (Institute of Packaging Professionals) aux Etats-Unis en 2024. \u00abLe bouchon SnapSlide est particuli\u00e8rement adapt\u00e9 pour les 60 millions d\u2019Am\u00e9ricains ayant des probl\u00e8mes de dext\u00e9rit\u00e9, comme ceux souffrant d\u2019arthrite ou d\u2019AVC\/paralysie, ou amput\u00e9s d\u2019un membre, explique Rocky Batzel. \u00abPour ces personnes, les fermetures pharmaceutiques conventionnelles sont pratiquement impossibles \u00e0 ouvrir, \u00e0 doser, et \u00e0 refermer avec un seul bras. Lors des tests, 90% des consommateurs ont pr\u00e9f\u00e9r\u00e9 SnapSlide, et beaucoup ont indiqu\u00e9 qu\u2019ils seraient plus fid\u00e8les aux marques l\u2019adoptant. Ce design inclusif am\u00e9liore \u00e0 la fois l\u2019exp\u00e9rience utilisateur et l\u2019observance des traitements\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>En France, environ 60% des cas d\u2019intoxication accidentelle chez les enfants sont li\u00e9s aux m\u00e9dicaments, les plus jeunes (1 \u00e0 3 ans) \u00e9tant particuli\u00e8rement \u00e0 risque. En r\u00e9ponse aux r\u00e9glementations mondiales et aux attentes des industries, les fabricants (SGD Pharma, Neopac, Sanner Group, SnapSlide, Rieke, Silgan Dispensing) d\u00e9veloppent des emballages certifi\u00e9s r\u00e9sistants aux enfants (Child [&hellip;]<\/p>","protected":false},"author":2,"featured_media":42218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":0,"footnotes":""},"categories":[26,81,7,65],"tags":[],"class_list":["post-42217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterale","category-packaging","category-pharmacie","category-vu-dans-le-mag"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9 - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9 - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"En France, environ 60% des cas d\u2019intoxication accidentelle chez les enfants sont li\u00e9s aux m\u00e9dicaments, les plus jeunes (1 \u00e0 3 ans) \u00e9tant particuli\u00e8rement \u00e0 risque. En r\u00e9ponse aux r\u00e9glementations mondiales et aux attentes des industries, les fabricants (SGD Pharma, Neopac, Sanner Group, SnapSlide, Rieke, Silgan Dispensing) d\u00e9veloppent des emballages certifi\u00e9s r\u00e9sistants aux enfants (Child [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T16:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-06T16:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9\",\"datePublished\":\"2024-09-30T16:08:00+00:00\",\"dateModified\":\"2024-10-06T16:10:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\"},\"wordCount\":1139,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg\",\"articleSection\":[\"Barre lat\u00e9rale\",\"Packaging\",\"Pharmacie\",\"Vu dans le mag\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\",\"name\":\"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9 - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg\",\"datePublished\":\"2024-09-30T16:08:00+00:00\",\"dateModified\":\"2024-10-06T16:10:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg\",\"width\":800,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9 - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/","og_locale":"en_GB","og_type":"article","og_title":"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9 - Emballage Digest","og_description":"En France, environ 60% des cas d\u2019intoxication accidentelle chez les enfants sont li\u00e9s aux m\u00e9dicaments, les plus jeunes (1 \u00e0 3 ans) \u00e9tant particuli\u00e8rement \u00e0 risque. En r\u00e9ponse aux r\u00e9glementations mondiales et aux attentes des industries, les fabricants (SGD Pharma, Neopac, Sanner Group, SnapSlide, Rieke, Silgan Dispensing) d\u00e9veloppent des emballages certifi\u00e9s r\u00e9sistants aux enfants (Child [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/","og_site_name":"Emballage Digest","article_published_time":"2024-09-30T16:08:00+00:00","article_modified_time":"2024-10-06T16:10:16+00:00","og_image":[{"width":800,"height":571,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9","datePublished":"2024-09-30T16:08:00+00:00","dateModified":"2024-10-06T16:10:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/"},"wordCount":1139,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg","articleSection":["Barre lat\u00e9rale","Packaging","Pharmacie","Vu dans le mag"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/","url":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/","name":"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9 - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg","datePublished":"2024-09-30T16:08:00+00:00","dateModified":"2024-10-06T16:10:16+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/SGD-PHARMA-GAMME-ENSIEMO-10ML.jpg","width":800,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/emballages-pharma-priorite-a-la-securite-des-enfants-et-a-la-durabilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Emballages pharma : priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 des enfants et \u00e0 la durabilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=42217"}],"version-history":[{"count":1,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42217\/revisions"}],"predecessor-version":[{"id":42219,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42217\/revisions\/42219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/42218"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=42217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=42217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=42217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}