{"id":42220,"date":"2024-09-30T18:10:00","date_gmt":"2024-09-30T16:10:00","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=42220"},"modified":"2024-10-06T18:12:13","modified_gmt":"2024-10-06T16:12:13","slug":"trioworld-poursuit-sa-strategie-de-croissance","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/trioworld-poursuit-sa-strategie-de-croissance\/","title":{"rendered":"Trioworld poursuit sa strat\u00e9gie de croissance"},"content":{"rendered":"<p>Quelques mois apr\u00e8s l\u2019acquisition de Wentus, le groupe su\u00e9dois Trioworld annonce avoir sign\u00e9 cet \u00e9t\u00e9 un accord pour acqu\u00e9rir les soci\u00e9t\u00e9s fran\u00e7aises Palamy et BRJ (Beaudet et Ren\u00e9 Jean Emballage) \u2013 fournisseurs des solutions d\u2019emballage \u00e0 haute performance pour le pain, les produits surgel\u00e9s et d\u2019autres applications d\u2019emballage grand public \u2013 par le biais d\u2019un achat de toutes les actions de Sopal.<\/p>\n\n\n\n<p>Ce dernier est l\u2019un des principaux producteurs et fournisseurs fran\u00e7ais de films en poly\u00e9thyl\u00e8ne et de solutions d\u2019emballage, avec un chiffre d\u2019affaires de 83 millions d\u2019euros (2022) et environ 250 employ\u00e9s. \u00abCette acquisition nous donnera l\u2019occasion de renforcer notre position sur le march\u00e9 des solutions d\u2019emballage alimentaire avanc\u00e9es en Europe. Les deux entreprises ont une longue exp\u00e9rience de la fourniture de produits de qualit\u00e9 sup\u00e9rieure avec un service de qualit\u00e9 sup\u00e9rieure et nous avons une grande confiance dans l\u2019\u00e9quipe de Palamy-BRJ. Nous voyons un grand potentiel dans le fait d\u2019unir nos forces et de poursuivre ensemble un parcours couronn\u00e9 de succ\u00e8s\u00bb, d\u00e9clare Andreas Malmberg, pdg du groupe Trioworld. La transaction est soumise aux conditions de cl\u00f4ture habituelles et \u00e0 l\u2019approbation des autorit\u00e9s fran\u00e7aises.\u00a0Le groupe Trioworld d\u00e9tiendra, une fois la transaction r\u00e9alis\u00e9e,\u00a0100% des actions.<\/p>","protected":false},"excerpt":{"rendered":"<p>Quelques mois apr\u00e8s l\u2019acquisition de Wentus, le groupe su\u00e9dois Trioworld annonce avoir sign\u00e9 cet \u00e9t\u00e9 un accord pour acqu\u00e9rir les soci\u00e9t\u00e9s fran\u00e7aises Palamy et BRJ (Beaudet et Ren\u00e9 Jean Emballage) \u2013 fournisseurs des solutions d\u2019emballage \u00e0 haute performance pour le pain, les produits surgel\u00e9s et d\u2019autres applications d\u2019emballage grand public \u2013 par le biais d\u2019un [&hellip;]<\/p>","protected":false},"author":2,"featured_media":42221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":2,"footnotes":""},"categories":[5,28,10,81,65],"tags":[],"class_list":["post-42220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentaire","category-article-entier","category-materiaux","category-packaging","category-vu-dans-le-mag"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trioworld poursuit sa strat\u00e9gie de croissance - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/trioworld-poursuit-sa-strategie-de-croissance\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trioworld poursuit sa strat\u00e9gie de croissance - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Quelques mois apr\u00e8s l\u2019acquisition de Wentus, le groupe su\u00e9dois Trioworld annonce avoir sign\u00e9 cet \u00e9t\u00e9 un accord pour acqu\u00e9rir les soci\u00e9t\u00e9s fran\u00e7aises Palamy et BRJ (Beaudet et Ren\u00e9 Jean Emballage) \u2013 fournisseurs des solutions d\u2019emballage \u00e0 haute performance pour le pain, les produits surgel\u00e9s et d\u2019autres applications d\u2019emballage grand public \u2013 par le biais d\u2019un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/trioworld-poursuit-sa-strategie-de-croissance\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T16:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-06T16:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Trioworld poursuit sa strat\u00e9gie de croissance\",\"datePublished\":\"2024-09-30T16:10:00+00:00\",\"dateModified\":\"2024-10-06T16:12:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/\"},\"wordCount\":233,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg\",\"articleSection\":[\"Alimentaire\",\"Article entier\",\"Mat\u00e9riaux\",\"Packaging\",\"Vu dans le mag\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/\",\"name\":\"Trioworld poursuit sa strat\u00e9gie de croissance - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg\",\"datePublished\":\"2024-09-30T16:10:00+00:00\",\"dateModified\":\"2024-10-06T16:12:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg\",\"width\":800,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trioworld poursuit sa strat\u00e9gie de croissance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trioworld poursuit sa strat\u00e9gie de croissance - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/trioworld-poursuit-sa-strategie-de-croissance\/","og_locale":"en_GB","og_type":"article","og_title":"Trioworld poursuit sa strat\u00e9gie de croissance - Emballage Digest","og_description":"Quelques mois apr\u00e8s l\u2019acquisition de Wentus, le groupe su\u00e9dois Trioworld annonce avoir sign\u00e9 cet \u00e9t\u00e9 un accord pour acqu\u00e9rir les soci\u00e9t\u00e9s fran\u00e7aises Palamy et BRJ (Beaudet et Ren\u00e9 Jean Emballage) \u2013 fournisseurs des solutions d\u2019emballage \u00e0 haute performance pour le pain, les produits surgel\u00e9s et d\u2019autres applications d\u2019emballage grand public \u2013 par le biais d\u2019un [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/trioworld-poursuit-sa-strategie-de-croissance\/","og_site_name":"Emballage Digest","article_published_time":"2024-09-30T16:10:00+00:00","article_modified_time":"2024-10-06T16:12:13+00:00","og_image":[{"width":800,"height":571,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Trioworld poursuit sa strat\u00e9gie de croissance","datePublished":"2024-09-30T16:10:00+00:00","dateModified":"2024-10-06T16:12:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/"},"wordCount":233,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg","articleSection":["Alimentaire","Article entier","Mat\u00e9riaux","Packaging","Vu dans le mag"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/","url":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/","name":"Trioworld poursuit sa strat\u00e9gie de croissance - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg","datePublished":"2024-09-30T16:10:00+00:00","dateModified":"2024-10-06T16:12:13+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/10\/trioworld-palamy.jpg","width":800,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/trioworld-poursuit-sa-strategie-de-croissance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Trioworld poursuit sa strat\u00e9gie de croissance"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=42220"}],"version-history":[{"count":1,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42220\/revisions"}],"predecessor-version":[{"id":42222,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42220\/revisions\/42222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/42221"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=42220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=42220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=42220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}