{"id":42615,"date":"2024-11-12T09:07:42","date_gmt":"2024-11-12T08:07:42","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=42615"},"modified":"2024-11-12T09:07:44","modified_gmt":"2024-11-12T08:07:44","slug":"bayer-commercialise-un-blister-mono-materiau-avec-liveo-research","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/","title":{"rendered":"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research"},"content":{"rendered":"<p><strong>Bayer annonce le lancement d\u2019un blister en PET, le premier du genre dans le secteur de la sant\u00e9, pour sa marque, Aleve. R\u00e9alis\u00e9e en partenariat avec le sp\u00e9cialiste de l\u2019emballage pharmaceutique Liveo Research, cette alternative au blister en PVC affiche une empreinte carbone r\u00e9duite de 38 %<sup>[1]<\/sup>. Lanc\u00e9e d\u2019abord aux Pays-Bas, la solution sera progressivement \u00e9tendue \u00e0 tous les blisters OTC du groupe, annonce son fabricant.<\/strong><\/p>\n\n\n\n<p>Outre une empreinte carbone r\u00e9duite, le nouvel emballage minimise les impacts sur la biodiversit\u00e9 en consommant 78% moins d\u2019eau et 53% moins de terres (par unit\u00e9). Le blister a \u00e9galement \u00e9t\u00e9 all\u00e9g\u00e9 de 18% par unit\u00e9 par rapport \u00e0 l\u2019emballage actuel. Le lancement sur le march\u00e9 est le r\u00e9sultat de nombreuses ann\u00e9es de pr\u00e9paration et de coop\u00e9ration entre les experts de Bayer et de Liveo Research, indiquent les deux partenaires.<\/p>\n\n\n\n<p>\u00ab Notre objectif est de transformer nos emballages pour offrir des exp\u00e9riences remarquables \u00e0 nos consommateurs tout en minimisant notre impact environnemental et, en fin de compte, en cr\u00e9ant des solutions circulaires \u00bb, a d\u00e9clar\u00e9 Chris Padain, vice-pr\u00e9sident et chef mondial de la conception, de l\u2019emballage, de l\u2019exp\u00e9rience produit et de la durabilit\u00e9 pour la division Consumer Health de Bayer.<\/p>\n\n\n\n<p>\u00ab Avec l\u2019introduction de notre blister en PET mono-mat\u00e9riau dans la gamme de produits Aleve de Bayer, nous avons prouv\u00e9 qu\u2019il est possible d\u2019offrir des emballages blister plus durables \u00e0 grande \u00e9chelle \u00e0 l\u2019\u00e9chelle mondiale. Les d\u00e9chets et le carbone peuvent d\u00e9j\u00e0 \u00eatre \u00e9conomis\u00e9s aujourd\u2019hui \u00bb, d\u00e9clare le Dr Carsten Heldmann, pdg de Liveo Research.<\/p>\n\n\n\n<p>Bayer travaille \u00e0 l\u2019\u00e9chelle de l\u2019industrie en partenariat avec la Global Self-Care Federation et le Blister Pack Collective, et s\u2019est r\u00e9cemment jointe \u00e0 The Recycling Partnership pour acc\u00e9l\u00e9rer les progr\u00e8s et cr\u00e9er un changement syst\u00e9mique. Il s\u2019agit notamment de mener des recherches sur de nouvelles fa\u00e7ons d\u2019emballer les m\u00e9dicaments sans ordonnance et de concevoir des solutions d\u2019emballage circulaires tout en pr\u00e9servant l\u2019efficacit\u00e9, la qualit\u00e9 et la s\u00e9curit\u00e9 des produits, ainsi que de travailler avec des partenaires tout au long de la cha\u00eene de valeur pour innover en mati\u00e8re de solutions d\u2019emballage et am\u00e9liorer les infrastructures de recyclage.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bayer annonce le lancement d\u2019un blister en PET, le premier du genre dans le secteur de la sant\u00e9, pour sa marque, Aleve. R\u00e9alis\u00e9e en partenariat avec le sp\u00e9cialiste de l\u2019emballage pharmaceutique Liveo Research, cette alternative au blister en PVC affiche une empreinte carbone r\u00e9duite de 38 %[1]. Lanc\u00e9e d\u2019abord aux Pays-Bas, la solution sera progressivement [&hellip;]<\/p>","protected":false},"author":2,"featured_media":42616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":12,"footnotes":""},"categories":[28,4],"tags":[],"class_list":["post-42615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-entier","category-lineaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Bayer annonce le lancement d\u2019un blister en PET, le premier du genre dans le secteur de la sant\u00e9, pour sa marque, Aleve. R\u00e9alis\u00e9e en partenariat avec le sp\u00e9cialiste de l\u2019emballage pharmaceutique Liveo Research, cette alternative au blister en PVC affiche une empreinte carbone r\u00e9duite de 38 %[1]. Lanc\u00e9e d\u2019abord aux Pays-Bas, la solution sera progressivement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T08:07:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T08:07:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research\",\"datePublished\":\"2024-11-12T08:07:42+00:00\",\"dateModified\":\"2024-11-12T08:07:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\"},\"wordCount\":395,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg\",\"articleSection\":[\"Article entier\",\"Lin\u00e9aires\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\",\"name\":\"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg\",\"datePublished\":\"2024-11-12T08:07:42+00:00\",\"dateModified\":\"2024-11-12T08:07:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/","og_locale":"en_GB","og_type":"article","og_title":"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research - Emballage Digest","og_description":"Bayer annonce le lancement d\u2019un blister en PET, le premier du genre dans le secteur de la sant\u00e9, pour sa marque, Aleve. R\u00e9alis\u00e9e en partenariat avec le sp\u00e9cialiste de l\u2019emballage pharmaceutique Liveo Research, cette alternative au blister en PVC affiche une empreinte carbone r\u00e9duite de 38 %[1]. Lanc\u00e9e d\u2019abord aux Pays-Bas, la solution sera progressivement [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/","og_site_name":"Emballage Digest","article_published_time":"2024-11-12T08:07:42+00:00","article_modified_time":"2024-11-12T08:07:44+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research","datePublished":"2024-11-12T08:07:42+00:00","dateModified":"2024-11-12T08:07:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/"},"wordCount":395,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg","articleSection":["Article entier","Lin\u00e9aires"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/","url":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/","name":"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg","datePublished":"2024-11-12T08:07:42+00:00","dateModified":"2024-11-12T08:07:44+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2024\/11\/bayer.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/bayer-commercialise-un-blister-mono-materiau-avec-liveo-research\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Bayer commercialise un blister mono-mat\u00e9riau avec Liveo Research"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=42615"}],"version-history":[{"count":2,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42615\/revisions"}],"predecessor-version":[{"id":42618,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/42615\/revisions\/42618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/42616"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=42615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=42615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=42615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}