{"id":43397,"date":"2025-01-22T00:53:29","date_gmt":"2025-01-21T23:53:29","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=43397"},"modified":"2025-01-22T00:53:31","modified_gmt":"2025-01-21T23:53:31","slug":"alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/","title":{"rendered":"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers"},"content":{"rendered":"<p><strong>Alliance Machine Systems International, fabricant d&rsquo;\u00e9quipements d&#8217;emballage automatis\u00e9s pour la production de bo\u00eetes en carton ondul\u00e9 du groupe Barry-Wehmiller depuis 2015, reprend JD Engineers, constructeur de colleuses-plieuses sp\u00e9cialis\u00e9es de haute qualit\u00e9. Gr\u00e2ce \u00e0 ce partenariat strat\u00e9gique, la premi\u00e8re solution tout-en-un am\u00e9liorera l&rsquo;efficacit\u00e9 et la qualit\u00e9 de la production pour les clients.<\/strong><\/p>\n\n\n\n<p>\u00ab Apr\u00e8s plus de dix ans de collaboration fructueuse en Europe, Alliance et JD Engineers ont d\u00e9cid\u00e9 de faire partie de la m\u00eame structure commerciale. Cette acquisition est une \u00e9tape cruciale dans le renforcement de notre position en tant que fournisseur de solutions compl\u00e8tes pour nos clients. Au cours des 25 derni\u00e8res ann\u00e9es, JD Engineers s&rsquo;est impos\u00e9e comme une entreprise solide, fiable, innovante et dynamique dans l&rsquo;industrie du carton ondul\u00e9 et de la bo\u00eete pliante. Son succ\u00e8s est d\u00fb \u00e0 l&rsquo;enthousiasme et au travail acharn\u00e9 de ses collaborateurs&nbsp;\u00bb, commente Marius Batrin, pr\u00e9sident d&rsquo;Alliance Machine Systems International.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance2.jpg\" alt=\"\" class=\"wp-image-43399\" width=\"830\" height=\"467\" srcset=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance2.jpg 800w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance2-300x169.jpg 300w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance2-768x432.jpg 768w, https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance2-18x10.jpg 18w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/figure>\n\n\n\n<p>Au cours des 25 derni\u00e8res ann\u00e9es, JD Engineers s&rsquo;est impos\u00e9e comme une entreprise solide, fiable, innovante et dynamique dans l&rsquo;industrie du carton ondul\u00e9 et de la bo\u00eete pliante. Toute l&rsquo;\u00e9quipe de JD Engineers restera en place, continuera \u00e0 se d\u00e9velopper et \u00e0 mettre au point des \u00e9quipements de pointe, avec le soutien d\u00e9sormais d&rsquo;Alliance Machine Systems en mati\u00e8re d&rsquo;ing\u00e9nierie, de ventes et de service \u00e0 la client\u00e8le, afin de compl\u00e9ter la gamme de produits Alliance J&amp;L.<\/p>\n\n\n\n<p>\u00ab L&rsquo;investissement d&rsquo;Alliance Machine Systems International dans JD Engineers t\u00e9moigne de notre engagement en faveur de l&rsquo;innovation et de la technologie unique que nous avons d\u00e9velopp\u00e9e \u00bb, a d\u00e9clar\u00e9 Jasper Kruizinga, fondateur et directeur technique de JD Engineers. \u00ab Ce partenariat repr\u00e9sente pour nous une opportunit\u00e9 passionnante de renforcer notre impact en tirant parti de notre expertise combin\u00e9e et de notre culture commune. Depuis sa cr\u00e9ation, JD Engineers s&rsquo;est d\u00e9velopp\u00e9e et a prosp\u00e9r\u00e9 en fournissant \u00e0 ses clients des solutions fiables et hautement innovantes. Nous sommes ravis d&rsquo;unir nos forces \u00e0 celles d&rsquo;Alliance, une entreprise tr\u00e8s respect\u00e9e qui nous permettra de nous positionner pour de futurs succ\u00e8s et de continuer \u00e0 construire notre r\u00e9putation de leader de l&rsquo;industrie \u00bb.<\/p>\n\n\n\n<p>\u00ab&nbsp;Ce partenariat nous permettra d&rsquo;offrir une valeur ajout\u00e9e encore plus grande \u00e0 nos clients \u00bb, a d\u00e9clar\u00e9 Doeke Holtrop, fondateur et directeur commercial de JD Engineers. \u00ab En combinant nos solutions innovantes avec les ressources et l&rsquo;expertise d&rsquo;Alliance Machine Systems International, nous serons en mesure d&rsquo;acc\u00e9l\u00e9rer notre croissance, d&rsquo;am\u00e9liorer nos services et d&rsquo;\u00e9tendre notre port\u00e9e. Ce partenariat est un excellent prolongement de notre strat\u00e9gie commerciale \u00e0 long terme \u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>Alliance Machine Systems International, fabricant d&rsquo;\u00e9quipements d&#8217;emballage automatis\u00e9s pour la production de bo\u00eetes en carton ondul\u00e9 du groupe Barry-Wehmiller depuis 2015, reprend JD Engineers, constructeur de colleuses-plieuses sp\u00e9cialis\u00e9es de haute qualit\u00e9. Gr\u00e2ce \u00e0 ce partenariat strat\u00e9gique, la premi\u00e8re solution tout-en-un am\u00e9liorera l&rsquo;efficacit\u00e9 et la qualit\u00e9 de la production pour les clients. \u00ab Apr\u00e8s plus de [&hellip;]<\/p>","protected":false},"author":2,"featured_media":43398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":7,"footnotes":""},"categories":[28,9],"tags":[],"class_list":["post-43397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-entier","category-materiel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Alliance Machine Systems International, fabricant d&rsquo;\u00e9quipements d&#8217;emballage automatis\u00e9s pour la production de bo\u00eetes en carton ondul\u00e9 du groupe Barry-Wehmiller depuis 2015, reprend JD Engineers, constructeur de colleuses-plieuses sp\u00e9cialis\u00e9es de haute qualit\u00e9. Gr\u00e2ce \u00e0 ce partenariat strat\u00e9gique, la premi\u00e8re solution tout-en-un am\u00e9liorera l&rsquo;efficacit\u00e9 et la qualit\u00e9 de la production pour les clients. \u00ab Apr\u00e8s plus de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T23:53:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T23:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers\",\"datePublished\":\"2025-01-21T23:53:29+00:00\",\"dateModified\":\"2025-01-21T23:53:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\"},\"wordCount\":478,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg\",\"articleSection\":[\"Article entier\",\"Mat\u00e9riel\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\",\"name\":\"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg\",\"datePublished\":\"2025-01-21T23:53:29+00:00\",\"dateModified\":\"2025-01-21T23:53:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg\",\"width\":800,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/","og_locale":"en_GB","og_type":"article","og_title":"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers - Emballage Digest","og_description":"Alliance Machine Systems International, fabricant d&rsquo;\u00e9quipements d&#8217;emballage automatis\u00e9s pour la production de bo\u00eetes en carton ondul\u00e9 du groupe Barry-Wehmiller depuis 2015, reprend JD Engineers, constructeur de colleuses-plieuses sp\u00e9cialis\u00e9es de haute qualit\u00e9. Gr\u00e2ce \u00e0 ce partenariat strat\u00e9gique, la premi\u00e8re solution tout-en-un am\u00e9liorera l&rsquo;efficacit\u00e9 et la qualit\u00e9 de la production pour les clients. \u00ab Apr\u00e8s plus de [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/","og_site_name":"Emballage Digest","article_published_time":"2025-01-21T23:53:29+00:00","article_modified_time":"2025-01-21T23:53:31+00:00","og_image":[{"width":800,"height":573,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers","datePublished":"2025-01-21T23:53:29+00:00","dateModified":"2025-01-21T23:53:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/"},"wordCount":478,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg","articleSection":["Article entier","Mat\u00e9riel"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/","url":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/","name":"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg","datePublished":"2025-01-21T23:53:29+00:00","dateModified":"2025-01-21T23:53:31+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/01\/alliance1.jpg","width":800,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/alliance-machine-systems-international-annonce-lacquisition-de-jd-engineers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Alliance Machine Systems International annonce l\u2019acquisition de JD Engineers"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/43397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=43397"}],"version-history":[{"count":2,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/43397\/revisions"}],"predecessor-version":[{"id":43401,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/43397\/revisions\/43401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/43398"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=43397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=43397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=43397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}