{"id":45469,"date":"2025-09-12T00:24:25","date_gmt":"2025-09-11T22:24:25","guid":{"rendered":"https:\/\/www.emballagedigest.fr\/?p=45469"},"modified":"2025-09-15T00:10:56","modified_gmt":"2025-09-14T22:10:56","slug":"tallineau-emballage-change-de-capital-et-de-direction","status":"publish","type":"post","link":"https:\/\/www.emballagedigest.fr\/en\/tallineau-emballage-change-de-capital-et-de-direction\/","title":{"rendered":"Tallineau Emballage change de capital et de direction"},"content":{"rendered":"<p><strong>Tallineau Emballage \u2013 PME sp\u00e9cialis\u00e9e de la transformation de carton ondul\u00e9 sur mesure et de la revente de consommables d\u2019emballage \u2013 annonce la r\u00e9organisation de son capital \u00e0 l\u2019occasion de sa transmission \u00e0 son \u00e9quipe de management.<\/strong><\/p>\n\n\n\n<p>La famille Brochard, actionnaire historique de cette PME familiale, centenaire, dirig\u00e9e depuis 2017 par Benjamin Brochard, a souhait\u00e9 passer le relais. Trois cadres exp\u00e9riment\u00e9s, impliqu\u00e9s de longue date dans le d\u00e9veloppement de l\u2019entreprise, se sont ainsi naturellement constitu\u00e9s en \u00e9quipe dirigeante pour assurer la continuit\u00e9 et pr\u00e9parer l\u2019avenir. Cette op\u00e9ration a \u00e9t\u00e9 rendue possible gr\u00e2ce \u00e0 l\u2019appui de Turenne Groupe, qui devient actionnaire minoritaire via son fonds r\u00e9gional Pays de la Loire Croissance 2, aux c\u00f4t\u00e9s de l\u2019\u00e9quipe de management constitu\u00e9e de C\u00e9line Le Borgne, pr\u00e9sidente et responsable administratif et financier&nbsp;; Fr\u00e9d\u00e9ric Bouligand, responsable de production et logistique \u2013 site du 44&nbsp;; et Franck Bonnaud, responsable de production \u2013 site du 85.<\/p>\n\n\n\n<p>\u00ab Nous sommes fiers de prendre la rel\u00e8ve d\u2019une entreprise au savoir-faire reconnu depuis plus de cent ans. Notre ambition est de rester fid\u00e8les aux valeurs humaines qui font la force de Tallineau Emballage, tout en d\u00e9ployant une nouvelle strat\u00e9gie commerciale et en renfor\u00e7ant notre engagement RSE \u00bb, d\u00e9clare C\u00e9line Le Borgne, pr\u00e9sidente de Tallineau Emballage.<\/p>\n\n\n\n<p>Forte des comp\u00e9tences et de l\u2019engagement de ses 42 collaborateurs, Tallineau Emballage entend consolider son r\u00f4le de partenaire de confiance pour ses clients et acc\u00e9l\u00e9rer son d\u00e9veloppement dans une logique de croissance responsable et durable. Benjamin Brochard accompagne cette transmission en conservant une participation au capital et en poursuivant ses fonctions op\u00e9rationnelles, notamment sur les volets achats et RSE.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tallineau Emballage \u2013 PME sp\u00e9cialis\u00e9e de la transformation de carton ondul\u00e9 sur mesure et de la revente de consommables d\u2019emballage \u2013 annonce la r\u00e9organisation de son capital \u00e0 l\u2019occasion de sa transmission \u00e0 son \u00e9quipe de management. La famille Brochard, actionnaire historique de cette PME familiale, centenaire, dirig\u00e9e depuis 2017 par Benjamin Brochard, a souhait\u00e9 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":45470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"iawp_total_views":4,"footnotes":""},"categories":[28,10],"tags":[],"class_list":["post-45469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-entier","category-materiaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tallineau Emballage change de capital et de direction - Emballage Digest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emballagedigest.fr\/en\/tallineau-emballage-change-de-capital-et-de-direction\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tallineau Emballage change de capital et de direction - Emballage Digest\" \/>\n<meta property=\"og:description\" content=\"Tallineau Emballage \u2013 PME sp\u00e9cialis\u00e9e de la transformation de carton ondul\u00e9 sur mesure et de la revente de consommables d\u2019emballage \u2013 annonce la r\u00e9organisation de son capital \u00e0 l\u2019occasion de sa transmission \u00e0 son \u00e9quipe de management. La famille Brochard, actionnaire historique de cette PME familiale, centenaire, dirig\u00e9e depuis 2017 par Benjamin Brochard, a souhait\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emballagedigest.fr\/en\/tallineau-emballage-change-de-capital-et-de-direction\/\" \/>\n<meta property=\"og:site_name\" content=\"Emballage Digest\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T22:24:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-14T22:10:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Duval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Duval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/\"},\"author\":{\"name\":\"Karine Duval\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\"},\"headline\":\"Tallineau Emballage change de capital et de direction\",\"datePublished\":\"2025-09-11T22:24:25+00:00\",\"dateModified\":\"2025-09-14T22:10:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/\"},\"wordCount\":302,\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg\",\"articleSection\":[\"Article entier\",\"Mat\u00e9riaux\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/\",\"name\":\"Tallineau Emballage change de capital et de direction - Emballage Digest\",\"isPartOf\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg\",\"datePublished\":\"2025-09-11T22:24:25+00:00\",\"dateModified\":\"2025-09-14T22:10:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg\",\"width\":800,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.emballagedigest.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tallineau Emballage change de capital et de direction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#website\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"name\":\"Emballage Digest\",\"description\":\"Revue professionnelle sur les emballages\",\"publisher\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emballagedigest.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#organization\",\"name\":\"Emballage Digest\",\"url\":\"https:\/\/www.emballagedigest.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"contentUrl\":\"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png\",\"width\":379,\"height\":75,\"caption\":\"Emballage Digest\"},\"image\":{\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f\",\"name\":\"Karine Duval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g\",\"caption\":\"Karine Duval\"},\"url\":\"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tallineau Emballage change de capital et de direction - Emballage Digest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emballagedigest.fr\/en\/tallineau-emballage-change-de-capital-et-de-direction\/","og_locale":"en_GB","og_type":"article","og_title":"Tallineau Emballage change de capital et de direction - Emballage Digest","og_description":"Tallineau Emballage \u2013 PME sp\u00e9cialis\u00e9e de la transformation de carton ondul\u00e9 sur mesure et de la revente de consommables d\u2019emballage \u2013 annonce la r\u00e9organisation de son capital \u00e0 l\u2019occasion de sa transmission \u00e0 son \u00e9quipe de management. La famille Brochard, actionnaire historique de cette PME familiale, centenaire, dirig\u00e9e depuis 2017 par Benjamin Brochard, a souhait\u00e9 [&hellip;]","og_url":"https:\/\/www.emballagedigest.fr\/en\/tallineau-emballage-change-de-capital-et-de-direction\/","og_site_name":"Emballage Digest","article_published_time":"2025-09-11T22:24:25+00:00","article_modified_time":"2025-09-14T22:10:56+00:00","og_image":[{"width":800,"height":548,"url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg","type":"image\/jpeg"}],"author":"Karine Duval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Karine Duval","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#article","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/"},"author":{"name":"Karine Duval","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f"},"headline":"Tallineau Emballage change de capital et de direction","datePublished":"2025-09-11T22:24:25+00:00","dateModified":"2025-09-14T22:10:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/"},"wordCount":302,"publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg","articleSection":["Article entier","Mat\u00e9riaux"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/","url":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/","name":"Tallineau Emballage change de capital et de direction - Emballage Digest","isPartOf":{"@id":"https:\/\/www.emballagedigest.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg","datePublished":"2025-09-11T22:24:25+00:00","dateModified":"2025-09-14T22:10:56+00:00","breadcrumb":{"@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#primaryimage","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2025\/09\/TALLINEAU.jpg","width":800,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.emballagedigest.fr\/tallineau-emballage-change-de-capital-et-de-direction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.emballagedigest.fr\/"},{"@type":"ListItem","position":2,"name":"Tallineau Emballage change de capital et de direction"}]},{"@type":"WebSite","@id":"https:\/\/www.emballagedigest.fr\/#website","url":"https:\/\/www.emballagedigest.fr\/","name":"Emballage Digest","description":"Revue professionnelle sur les emballages","publisher":{"@id":"https:\/\/www.emballagedigest.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emballagedigest.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.emballagedigest.fr\/#organization","name":"Emballage Digest","url":"https:\/\/www.emballagedigest.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","contentUrl":"https:\/\/www.emballagedigest.fr\/wp-content\/uploads\/2022\/07\/logo-ed.png","width":379,"height":75,"caption":"Emballage Digest"},"image":{"@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/76abe9f2b2ee4d3d520594c7a35da59f","name":"Karine Duval","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.emballagedigest.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f552799261cdd2e076e6677d780ef07bdb13aa4c196ab75b39abcbcdcae2d4e5?s=96&d=mm&r=g","caption":"Karine Duval"},"url":"https:\/\/www.emballagedigest.fr\/en\/author\/admin_karduv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/45469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/comments?post=45469"}],"version-history":[{"count":1,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/45469\/revisions"}],"predecessor-version":[{"id":45471,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/posts\/45469\/revisions\/45471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media\/45470"}],"wp:attachment":[{"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/media?parent=45469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/categories?post=45469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emballagedigest.fr\/en\/wp-json\/wp\/v2\/tags?post=45469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}